{"id":27003,"date":"2015-12-21T08:25:08","date_gmt":"2015-12-21T07:25:08","guid":{"rendered":"https:\/\/www.votorantimcimentos.es\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos\/"},"modified":"2024-04-18T11:30:39","modified_gmt":"2024-04-18T09:30:39","slug":"la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos","status":"publish","type":"post","link":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos\/","title":{"rendered":"La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba celebra tres a\u00f1os sin accidentes"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p style=\"text-align: justify;\">21 de diciembre.-La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba acaba de cumplir tres a\u00f1os sin accidentes con baja entre sus trabajadores directos. El compromiso de la plantilla con las medidas preventivas instauradas por la compa\u00f1\u00eda ha sido clave para que alcanzar este logro.<\/p>\n<p style=\"text-align: justify;\">Desde su llegada al mercado espa\u00f1ol, Votorantim Cimentos ha invertido un mill\u00f3n de euros en equipamiento, mejora de las instalaciones e iniciativas destinadas al cambio de comportamientos en las empresas del grupo. Fruto de estos esfuerzos, la siniestralidad del grupo en Espa\u00f1a se ha reducido de forma constante. As\u00ed, durante los \u00faltimos tres a\u00f1os la empresa ha conseguido reducir el \u00edndice global de siniestralidad m\u00e1s de un 80%.<\/p>\n<p style=\"text-align: justify;\">La seguridad y salud laboral tienen un car\u00e1cter prioritario para el grupo, que lleva a cabo diversas iniciativas de prevenci\u00f3n y concienciaci\u00f3n. Una de estas acciones en la que participa la f\u00e1brica cordobesa son los Di\u00e1logos Diarios de Seguridad, donde todos los trabajadores inician su jornada juntos, compartiendo un tema de seguridad, protagonizado cada d\u00eda por un trabajador y orientado a implicar a todos y cada uno de los miembros del equipo en la aplicaci\u00f3n de buenas pr\u00e1cticas en su d\u00eda a d\u00eda. Bajo el lema &#8216;La seguridad empieza por m\u00ed&#8217;, esta acci\u00f3n busca el compromiso personal de cada uno de los empleados. &#8220;Estamos mejorando pero a\u00fan queda mucho por hacer para lograr el objetivo Cero Accidentes. El comportamiento es el elemento principal a la hora de prevenir accidentes y el compromiso personal de cada uno de nosotros la clave para crear un ambiente de trabajo seguro&#8221;, ha afirmado Jos\u00e9 de la Vega, director de la f\u00e1brica de C\u00f3rdoba.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba acaba de cumplir tres a\u00f1os sin accidentes con baja entre sus trabajadores directos.<\/p>\n","protected":false},"author":1,"featured_media":25756,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[304,298],"tags":[],"class_list":["post-27003","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fabrica-de-cordova","category-sustentabilidade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba celebra tres a\u00f1os sin accidentes | Votorantim Cimentos Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba celebra tres a\u00f1os sin accidentes | Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba acaba de cumplir tres a\u00f1os sin accidentes con baja entre sus trabajadores directos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-21T07:25:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-18T09:30:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/3-anos-sin-accidentes-cosmos-cordoba.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"265\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"teconsite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"teconsite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos\\\/\"},\"author\":{\"name\":\"teconsite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\"},\"headline\":\"La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba celebra tres a\u00f1os sin accidentes\",\"datePublished\":\"2015-12-21T07:25:08+00:00\",\"dateModified\":\"2024-04-18T09:30:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos\\\/\"},\"wordCount\":911,\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/3-anos-sin-accidentes-cosmos-cordoba.jpg\",\"articleSection\":[\"F\u00e1brica de C\u00f3rdova\",\"Sustentabilidade\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos\\\/\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos\\\/\",\"name\":\"La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba celebra tres a\u00f1os sin accidentes | Votorantim Cimentos Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/3-anos-sin-accidentes-cosmos-cordoba.jpg\",\"datePublished\":\"2015-12-21T07:25:08+00:00\",\"dateModified\":\"2024-04-18T09:30:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/3-anos-sin-accidentes-cosmos-cordoba.jpg\",\"contentUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/3-anos-sin-accidentes-cosmos-cordoba.jpg\",\"width\":400,\"height\":265,\"caption\":\"3 a\u00f1os sin accidentes en la f\u00e1brica de C\u00f3rdoba\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba celebra tres a\u00f1os sin accidentes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/\",\"name\":\"Votorantim Cimentos Espa\u00f1a\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\",\"name\":\"teconsite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"caption\":\"teconsite\"},\"sameAs\":[\"https:\\\/\\\/www.votorantimcimentos.es\"],\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/author\\\/teconsite\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba celebra tres a\u00f1os sin accidentes | Votorantim Cimentos Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos\/","og_locale":"pt_PT","og_type":"article","og_title":"La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba celebra tres a\u00f1os sin accidentes | Votorantim Cimentos Espa\u00f1a","og_description":"La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba acaba de cumplir tres a\u00f1os sin accidentes con baja entre sus trabajadores directos.","og_url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos\/","og_site_name":"Votorantim Cimentos Espa\u00f1a","article_published_time":"2015-12-21T07:25:08+00:00","article_modified_time":"2024-04-18T09:30:39+00:00","og_image":[{"width":400,"height":265,"url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/3-anos-sin-accidentes-cosmos-cordoba.jpg","type":"image\/jpeg"}],"author":"teconsite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"teconsite","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos\/#article","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos\/"},"author":{"name":"teconsite","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d"},"headline":"La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba celebra tres a\u00f1os sin accidentes","datePublished":"2015-12-21T07:25:08+00:00","dateModified":"2024-04-18T09:30:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos\/"},"wordCount":911,"image":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/3-anos-sin-accidentes-cosmos-cordoba.jpg","articleSection":["F\u00e1brica de C\u00f3rdova","Sustentabilidade"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos\/","url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos\/","name":"La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba celebra tres a\u00f1os sin accidentes | Votorantim Cimentos Espa\u00f1a","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos\/#primaryimage"},"image":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/3-anos-sin-accidentes-cosmos-cordoba.jpg","datePublished":"2015-12-21T07:25:08+00:00","dateModified":"2024-04-18T09:30:39+00:00","author":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d"},"breadcrumb":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos\/#primaryimage","url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/3-anos-sin-accidentes-cosmos-cordoba.jpg","contentUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/3-anos-sin-accidentes-cosmos-cordoba.jpg","width":400,"height":265,"caption":"3 a\u00f1os sin accidentes en la f\u00e1brica de C\u00f3rdoba"},{"@type":"BreadcrumbList","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-tres-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.votorantimcimentos.es\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba celebra tres a\u00f1os sin accidentes"}]},{"@type":"WebSite","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#website","url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/","name":"Votorantim Cimentos Espa\u00f1a","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.votorantimcimentos.es\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d","name":"teconsite","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","caption":"teconsite"},"sameAs":["https:\/\/www.votorantimcimentos.es"],"url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/author\/teconsite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts\/27003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/comments?post=27003"}],"version-history":[{"count":1,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts\/27003\/revisions"}],"predecessor-version":[{"id":28383,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts\/27003\/revisions\/28383"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/media\/25756"}],"wp:attachment":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/media?parent=27003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/categories?post=27003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/tags?post=27003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}