{"id":27002,"date":"2016-01-18T08:25:08","date_gmt":"2016-01-18T07:25:08","guid":{"rendered":"https:\/\/www.votorantimcimentos.es\/noticias\/cementos-cosmos-apuesta-por-cordoba\/"},"modified":"2024-04-18T11:30:38","modified_gmt":"2024-04-18T09:30:38","slug":"cementos-cosmos-apuesta-por-cordoba","status":"publish","type":"post","link":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/cementos-cosmos-apuesta-por-cordoba\/","title":{"rendered":"Cementos Cosmos apuesta por C\u00f3rdoba incrementando su plantilla un 20% este a\u00f1o"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p style=\"text-align: justify;\">C\u00f3rdoba, 18 de enero de 2016.- Cementos Cosmos ha anunciado que recientemente ha cerrado varias operaciones que implican duplicar la producci\u00f3n en 2016. Esto significa que el horno estar\u00e1 operativo la mitad del a\u00f1o para lo que necesitar\u00e1 incrementar su plantilla un 20%. Adem\u00e1s, se generar\u00e1 m\u00e1s empleo indirecto, proporcional a la producci\u00f3n, en el transporte, los servicios y el mantenimiento de la instalaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Hasta ahora, la f\u00e1brica de Cementos Cosmos estaba operando al 25% de su capacidad y generaba unos 250 puestos de trabajo, de los que 80 son empleos directos.<\/p>\n<p style=\"text-align: justify;\">El director de la f\u00e1brica, Jos\u00e9 de la Vega, ha comentado: &#8220;Estamos muy satisfechos con esta noticia que supone generar m\u00e1s empleo en C\u00f3rdoba. Confiamos en poder mejorar la competitividad de nuestra instalaci\u00f3n con la introducci\u00f3n de la valorizaci\u00f3n energ\u00e9tica para operar en el mercado en las mismas condiciones que el resto de cementeras de Espa\u00f1a. Cementos Cosmos tiene un compromiso claro con esta f\u00e1brica y sus trabajadores y por ello dedicamos nuestro esfuerzo diario a convertirla en un ejemplo de buen hacer, eficiencia y competitividad&#8221;.<\/p>\n<p>Para ser m\u00e1s competitiva y poder mantener estos niveles de producci\u00f3n Cementos Cosmos prev\u00e9 sustituir una parte de sus combustibles f\u00f3siles procedentes del petr\u00f3leo por biomasa y por combustibles derivados de residuos no reciclables ni recuperables y cuyo destino ser\u00eda el vertedero.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cementos Cosmos ha anunciado que recientemente ha cerrado varias operaciones que implican duplicar la producci\u00f3n en 2016. Esto significa que necesitar\u00e1 incrementar su plantilla un 20%.<\/p>\n","protected":false},"author":1,"featured_media":25314,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[304,298],"tags":[],"class_list":["post-27002","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fabrica-de-cordova","category-sustentabilidade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cementos Cosmos apuesta por C\u00f3rdoba incrementando su plantilla un 20% este a\u00f1o | Votorantim Cimentos Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/cementos-cosmos-apuesta-por-cordoba\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cementos Cosmos apuesta por C\u00f3rdoba incrementando su plantilla un 20% este a\u00f1o | Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"Cementos Cosmos ha anunciado que recientemente ha cerrado varias operaciones que implican duplicar la producci\u00f3n en 2016. Esto significa que necesitar\u00e1 incrementar su plantilla un 20%.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/cementos-cosmos-apuesta-por-cordoba\/\" \/>\n<meta property=\"og:site_name\" content=\"Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-18T07:25:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-18T09:30:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/noticiacordoba.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1064\" \/>\n\t<meta property=\"og:image:height\" content=\"708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"teconsite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"teconsite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/cementos-cosmos-apuesta-por-cordoba\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/cementos-cosmos-apuesta-por-cordoba\\\/\"},\"author\":{\"name\":\"teconsite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\"},\"headline\":\"Cementos Cosmos apuesta por C\u00f3rdoba incrementando su plantilla un 20% este a\u00f1o\",\"datePublished\":\"2016-01-18T07:25:08+00:00\",\"dateModified\":\"2024-04-18T09:30:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/cementos-cosmos-apuesta-por-cordoba\\\/\"},\"wordCount\":853,\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/cementos-cosmos-apuesta-por-cordoba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/noticiacordoba.jpg\",\"articleSection\":[\"F\u00e1brica de C\u00f3rdova\",\"Sustentabilidade\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/cementos-cosmos-apuesta-por-cordoba\\\/\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/cementos-cosmos-apuesta-por-cordoba\\\/\",\"name\":\"Cementos Cosmos apuesta por C\u00f3rdoba incrementando su plantilla un 20% este a\u00f1o | Votorantim Cimentos Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/cementos-cosmos-apuesta-por-cordoba\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/cementos-cosmos-apuesta-por-cordoba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/noticiacordoba.jpg\",\"datePublished\":\"2016-01-18T07:25:08+00:00\",\"dateModified\":\"2024-04-18T09:30:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/cementos-cosmos-apuesta-por-cordoba\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/cementos-cosmos-apuesta-por-cordoba\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/cementos-cosmos-apuesta-por-cordoba\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/noticiacordoba.jpg\",\"contentUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/noticiacordoba.jpg\",\"width\":1064,\"height\":708,\"caption\":\"Noticias de la f\u00e1brica de C\u00f3rdoba\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/cementos-cosmos-apuesta-por-cordoba\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cementos Cosmos apuesta por C\u00f3rdoba incrementando su plantilla un 20% este a\u00f1o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/\",\"name\":\"Votorantim Cimentos Espa\u00f1a\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\",\"name\":\"teconsite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"caption\":\"teconsite\"},\"sameAs\":[\"https:\\\/\\\/www.votorantimcimentos.es\"],\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/author\\\/teconsite\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cementos Cosmos apuesta por C\u00f3rdoba incrementando su plantilla un 20% este a\u00f1o | Votorantim Cimentos Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/cementos-cosmos-apuesta-por-cordoba\/","og_locale":"pt_PT","og_type":"article","og_title":"Cementos Cosmos apuesta por C\u00f3rdoba incrementando su plantilla un 20% este a\u00f1o | Votorantim Cimentos Espa\u00f1a","og_description":"Cementos Cosmos ha anunciado que recientemente ha cerrado varias operaciones que implican duplicar la producci\u00f3n en 2016. Esto significa que necesitar\u00e1 incrementar su plantilla un 20%.","og_url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/cementos-cosmos-apuesta-por-cordoba\/","og_site_name":"Votorantim Cimentos Espa\u00f1a","article_published_time":"2016-01-18T07:25:08+00:00","article_modified_time":"2024-04-18T09:30:38+00:00","og_image":[{"width":1064,"height":708,"url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/noticiacordoba.jpg","type":"image\/jpeg"}],"author":"teconsite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"teconsite","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/cementos-cosmos-apuesta-por-cordoba\/#article","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/cementos-cosmos-apuesta-por-cordoba\/"},"author":{"name":"teconsite","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d"},"headline":"Cementos Cosmos apuesta por C\u00f3rdoba incrementando su plantilla un 20% este a\u00f1o","datePublished":"2016-01-18T07:25:08+00:00","dateModified":"2024-04-18T09:30:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/cementos-cosmos-apuesta-por-cordoba\/"},"wordCount":853,"image":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/cementos-cosmos-apuesta-por-cordoba\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/noticiacordoba.jpg","articleSection":["F\u00e1brica de C\u00f3rdova","Sustentabilidade"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/cementos-cosmos-apuesta-por-cordoba\/","url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/cementos-cosmos-apuesta-por-cordoba\/","name":"Cementos Cosmos apuesta por C\u00f3rdoba incrementando su plantilla un 20% este a\u00f1o | Votorantim Cimentos Espa\u00f1a","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/cementos-cosmos-apuesta-por-cordoba\/#primaryimage"},"image":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/cementos-cosmos-apuesta-por-cordoba\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/noticiacordoba.jpg","datePublished":"2016-01-18T07:25:08+00:00","dateModified":"2024-04-18T09:30:38+00:00","author":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d"},"breadcrumb":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/cementos-cosmos-apuesta-por-cordoba\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/cementos-cosmos-apuesta-por-cordoba\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/cementos-cosmos-apuesta-por-cordoba\/#primaryimage","url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/noticiacordoba.jpg","contentUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/noticiacordoba.jpg","width":1064,"height":708,"caption":"Noticias de la f\u00e1brica de C\u00f3rdoba"},{"@type":"BreadcrumbList","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/cementos-cosmos-apuesta-por-cordoba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.votorantimcimentos.es\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Cementos Cosmos apuesta por C\u00f3rdoba incrementando su plantilla un 20% este a\u00f1o"}]},{"@type":"WebSite","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#website","url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/","name":"Votorantim Cimentos Espa\u00f1a","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.votorantimcimentos.es\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d","name":"teconsite","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","caption":"teconsite"},"sameAs":["https:\/\/www.votorantimcimentos.es"],"url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/author\/teconsite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts\/27002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/comments?post=27002"}],"version-history":[{"count":1,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts\/27002\/revisions"}],"predecessor-version":[{"id":28381,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts\/27002\/revisions\/28381"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/media\/25314"}],"wp:attachment":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/media?parent=27002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/categories?post=27002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/tags?post=27002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}