{"id":27000,"date":"2016-03-18T08:25:08","date_gmt":"2016-03-18T07:25:08","guid":{"rendered":"https:\/\/www.votorantimcimentos.es\/noticias\/universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos\/"},"modified":"2024-04-18T11:30:37","modified_gmt":"2024-04-18T09:30:37","slug":"universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos","status":"publish","type":"post","link":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos\/","title":{"rendered":"Universitarios y colegiales de C\u00f3rdoba visitan la planta de Cementos Cosmos"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p style=\"text-align: justify;\">C\u00f3rdoba, 18 de marzo de 2016.- Cementos Cosmos ha recibido la visita de m\u00e1s de un centenar de estudiantes de la Universidad de C\u00f3rdoba y del Colegio Marista Cervantes. Un grupo de alumnos y profesores de la Escuela Polit\u00e9cnica Superior de B\u00e9lmez (Universidad de C\u00f3rdoba) ha examinado las instalaciones de la f\u00e1brica con el objetivo de reforzar los conocimientos te\u00f3ricos que han aprendido en clase, concretamente los incluidos en la asignatura de Tecnolog\u00eda de los Materiales. Durante la jornada pudieron analizar las fases del proceso de fabricaci\u00f3n de cemento, apoyados por el personal t\u00e9cnico de la empresa.<\/p>\n<p style=\"text-align: justify;\"> Seg\u00fan el director de la planta, Jos\u00e9 de la Vega &#8220;iniciativas como esta se enmarcan dentro de la pol\u00edtica de colaboraci\u00f3n e intercambio que la empresa tiene con el mundo acad\u00e9mico. Estas visitas fomentan una educaci\u00f3n m\u00e1s completa, enfocada a las necesidades de nuestros futuros t\u00e9cnicos en su desarrollo profesional&#8221;. La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba tiene una larga trayectoria de colaboraci\u00f3n el \u00e1mbito universitario. A lo largo de su historia ha recibido numerosas visitas y ha facilitado charlas informativas impartidas por t\u00e9cnicos de la empresa en diversos centros de formaci\u00f3n superior. S\u00f3lo el a\u00f1o pasado pasaron por sus instalaciones m\u00e1s de un centenar de universitarios.<\/p>\n<p style=\"text-align: justify;\"> Tambi\u00e9n los colegios e institutos<\/p>\n<p style=\"text-align: justify;\"> Por otro lado, la f\u00e1brica, de la mano de la Fundaci\u00f3n Laboral Andaluza del Cemento y el Medio Ambiente (FLACEMA), integrada por las empresas fabricantes de cemento de Andaluc\u00eda y por las dos organizaciones sindicales m\u00e1s representativas \u2013MCA-UGT Andaluc\u00eda y CCOO Construcci\u00f3n y Servicios Andaluc\u00eda, contin\u00faa dedicando esfuerzos a sensibilizar a los colegiales sobre la importancia que el desarrollo sostenible tiene, no solo en el \u00e1mbito industrial, sino tambi\u00e9n en el dom\u00e9stico. De esa manera se ha celebrado una jornada de car\u00e1cter informativo sobre medio ambiente, orientada a estudiantes de 4\u00ba de la ESO del colegio Marista Cervantes. Bajo el t\u00edtulo de &#8220;Desarrollo Sostenible: \u00bfResponsabilidad de todos?&#8221;<\/p>\n<p style=\"text-align: justify;\"> Desde que comenz\u00f3 el curso 2015\/2016 ya han pasado por las instalaciones de Cosmos estudiantes de diversos\u00a0 centros educativos, entre ellos, \u00c1ngel Saavedra, Gran Capit\u00e1n, El Tablero y Fuensanta, entre otros.<\/p>\n<p style=\"text-align: justify;\"> Durante los pr\u00f3ximos meses, otros centros educativos de la ciudad participar\u00e1n en este ciclo de jornadas que peri\u00f3dicamente y desde su constituci\u00f3n organiza la FLACEMA en toda la comunidad andaluza. Asimismo, todos aquellos centros educativos de secundaria, formaci\u00f3n profesional o universidades que est\u00e9n interesados en participar en este tipo de iniciativas pueden hacerlo contactando con la Fundaci\u00f3n FLACEMA. <a href=\"mailto:comunicacion@flacema.org\">comunicacion@flacema.org<\/a><\/p>\n<p style=\"text-align: justify;\"> Desde el 2009, a\u00f1o en el que se puso en marcha el programa &#8220;Desarrollo Sostenible. Responsabilidad de todos&#8221;\u00a0 FLACEMA ha organizado un total de 46 jornadas y\/o visitas de estudiantes, coordinadas y supervisadas por profesores y responsables de los centros educativos, a f\u00e1bricas andaluzas, de las cuales ocho han tenido lugar en C\u00f3rdoba. FLACEMA est\u00e1 declarada entidad de inter\u00e9s p\u00fablico y fundaci\u00f3n docente por la Consejer\u00eda de Educaci\u00f3n de la Junta de Andaluc\u00eda.\u200b<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cementos Cosmos ha recibido la visita de m\u00e1s de un centenar de estudiantes de la Universidad de C\u00f3rdoba y del Colegio Marista Cervantes.<\/p>\n","protected":false},"author":1,"featured_media":25748,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[304,298],"tags":[],"class_list":["post-27000","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fabrica-de-cordova","category-sustentabilidade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Universitarios y colegiales de C\u00f3rdoba visitan la planta de Cementos Cosmos | Votorantim Cimentos Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Universitarios y colegiales de C\u00f3rdoba visitan la planta de Cementos Cosmos | Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"Cementos Cosmos ha recibido la visita de m\u00e1s de un centenar de estudiantes de la Universidad de C\u00f3rdoba y del Colegio Marista Cervantes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos\/\" \/>\n<meta property=\"og:site_name\" content=\"Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-18T07:25:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-18T09:30:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/visita-universitarios.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"teconsite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"teconsite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos\\\/\"},\"author\":{\"name\":\"teconsite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\"},\"headline\":\"Universitarios y colegiales de C\u00f3rdoba visitan la planta de Cementos Cosmos\",\"datePublished\":\"2016-03-18T07:25:08+00:00\",\"dateModified\":\"2024-04-18T09:30:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos\\\/\"},\"wordCount\":1149,\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/visita-universitarios.jpg\",\"articleSection\":[\"F\u00e1brica de C\u00f3rdova\",\"Sustentabilidade\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos\\\/\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos\\\/\",\"name\":\"Universitarios y colegiales de C\u00f3rdoba visitan la planta de Cementos Cosmos | Votorantim Cimentos Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/visita-universitarios.jpg\",\"datePublished\":\"2016-03-18T07:25:08+00:00\",\"dateModified\":\"2024-04-18T09:30:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/visita-universitarios.jpg\",\"contentUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/visita-universitarios.jpg\",\"width\":400,\"height\":300,\"caption\":\"Visita de universitarios a las f\u00e1bricas de Votorantim Cimentos Espa\u00f1a\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Universitarios y colegiales de C\u00f3rdoba visitan la planta de Cementos Cosmos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/\",\"name\":\"Votorantim Cimentos Espa\u00f1a\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\",\"name\":\"teconsite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"caption\":\"teconsite\"},\"sameAs\":[\"https:\\\/\\\/www.votorantimcimentos.es\"],\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/author\\\/teconsite\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Universitarios y colegiales de C\u00f3rdoba visitan la planta de Cementos Cosmos | Votorantim Cimentos Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos\/","og_locale":"pt_PT","og_type":"article","og_title":"Universitarios y colegiales de C\u00f3rdoba visitan la planta de Cementos Cosmos | Votorantim Cimentos Espa\u00f1a","og_description":"Cementos Cosmos ha recibido la visita de m\u00e1s de un centenar de estudiantes de la Universidad de C\u00f3rdoba y del Colegio Marista Cervantes.","og_url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos\/","og_site_name":"Votorantim Cimentos Espa\u00f1a","article_published_time":"2016-03-18T07:25:08+00:00","article_modified_time":"2024-04-18T09:30:37+00:00","og_image":[{"width":400,"height":300,"url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/visita-universitarios.jpg","type":"image\/jpeg"}],"author":"teconsite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"teconsite","Tempo estimado de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos\/#article","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos\/"},"author":{"name":"teconsite","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d"},"headline":"Universitarios y colegiales de C\u00f3rdoba visitan la planta de Cementos Cosmos","datePublished":"2016-03-18T07:25:08+00:00","dateModified":"2024-04-18T09:30:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos\/"},"wordCount":1149,"image":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/visita-universitarios.jpg","articleSection":["F\u00e1brica de C\u00f3rdova","Sustentabilidade"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos\/","url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos\/","name":"Universitarios y colegiales de C\u00f3rdoba visitan la planta de Cementos Cosmos | Votorantim Cimentos Espa\u00f1a","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos\/#primaryimage"},"image":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/visita-universitarios.jpg","datePublished":"2016-03-18T07:25:08+00:00","dateModified":"2024-04-18T09:30:37+00:00","author":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d"},"breadcrumb":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos\/#primaryimage","url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/visita-universitarios.jpg","contentUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/visita-universitarios.jpg","width":400,"height":300,"caption":"Visita de universitarios a las f\u00e1bricas de Votorantim Cimentos Espa\u00f1a"},{"@type":"BreadcrumbList","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/universitarios-y-colegiales-de-cordoba-visitan-la-planta-de-cementos-cosmos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.votorantimcimentos.es\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Universitarios y colegiales de C\u00f3rdoba visitan la planta de Cementos Cosmos"}]},{"@type":"WebSite","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#website","url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/","name":"Votorantim Cimentos Espa\u00f1a","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.votorantimcimentos.es\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d","name":"teconsite","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","caption":"teconsite"},"sameAs":["https:\/\/www.votorantimcimentos.es"],"url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/author\/teconsite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts\/27000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/comments?post=27000"}],"version-history":[{"count":1,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts\/27000\/revisions"}],"predecessor-version":[{"id":28379,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts\/27000\/revisions\/28379"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/media\/25748"}],"wp:attachment":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/media?parent=27000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/categories?post=27000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/tags?post=27000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}