{"id":26983,"date":"2016-06-20T08:25:08","date_gmt":"2016-06-20T06:25:08","guid":{"rendered":"https:\/\/www.votorantimcimentos.es\/noticias\/mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla\/"},"modified":"2024-04-18T11:30:11","modified_gmt":"2024-04-18T09:30:11","slug":"mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla","status":"publish","type":"post","link":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla\/","title":{"rendered":"M\u00e1s de 300 personas visitan la f\u00e1brica de Cementos Cosmos en Niebla"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p style=\"text-align: justify;\">\u200bNiebla, 20 de junio de 2016.-La f\u00e1brica de Cementos Cosmos de Niebla ha celebrado un d\u00eda de puertas abiertas, en el que m\u00e1s de 300 personas han podido disfrutar de una agradable jornada visitando las instalaciones. T\u00e9cnicos de la planta acompa\u00f1aron a los visitantes y respondieron a las preguntas de los asistentes, que conocieron de primera mano el proceso de producci\u00f3n de un material de construcci\u00f3n imprescindible para el desarrollo econ\u00f3mico y social. Los participantes recibieron un obsequio al final del recorrido y compartieron impresiones mientras disfrutaban de un aperitivo.<\/p>\n<p style=\"text-align: justify;\">La jornada de puertas abiertas se enmarca dentro de la pol\u00edtica de Cementos Cosmos de relaci\u00f3n con el entorno y colaboraci\u00f3n con la comunidad. La planta lleva varios a\u00f1os abriendo sus puertas a los vecinos de la comarca con el objetivo de dar a conocer su actividad. El pasado mes de marzo, los estudiantes del instituto Delgado Hern\u00e1ndez (Bollulos Par del Condado) pudieron conocer las instalaciones en el transcurso de una jornada sobre desarrollo sostenible.<\/p>\n<p>La f\u00e1brica de Cementos Cosmos en Niebla es uno de los principales activos de Votorantim Cimentos en Andaluc\u00eda. Con una producci\u00f3n el a\u00f1o pasado de cerca de 453.000 toneladas de cl\u00ednker (producto intermedio en la fabricaci\u00f3n de cemento), esta planta apoya el desarrollo de su entorno contribuyendo con diferentes organizaciones e instituciones locales. Recientemente, en el marco del convenio firmado con el Ayuntamiento para fomentar el deporte de base durante los pr\u00f3ximos a\u00f1os, la cementera ha instalado asientos en las gradas del polideportivo de Niebla.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La f\u00e1brica de Cementos Cosmos de Niebla ha celebrado un d\u00eda de puertas abiertas, en el que m\u00e1s de 300 personas han podido disfrutar de una agradable jornada visitando las instalaciones.<\/p>\n","protected":false},"author":1,"featured_media":25687,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[305,298],"tags":[],"class_list":["post-26983","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fabrica-de-niebla","category-sustentabilidade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e1s de 300 personas visitan la f\u00e1brica de Cementos Cosmos en Niebla | Votorantim Cimentos Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1s de 300 personas visitan la f\u00e1brica de Cementos Cosmos en Niebla | Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"La f\u00e1brica de Cementos Cosmos de Niebla ha celebrado un d\u00eda de puertas abiertas, en el que m\u00e1s de 300 personas han podido disfrutar de una agradable jornada visitando las instalaciones.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla\/\" \/>\n<meta property=\"og:site_name\" content=\"Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-20T06:25:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-18T09:30:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/visita-niebla.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"teconsite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"teconsite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla\\\/\"},\"author\":{\"name\":\"teconsite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\"},\"headline\":\"M\u00e1s de 300 personas visitan la f\u00e1brica de Cementos Cosmos en Niebla\",\"datePublished\":\"2016-06-20T06:25:08+00:00\",\"dateModified\":\"2024-04-18T09:30:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla\\\/\"},\"wordCount\":885,\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/visita-niebla.jpg\",\"articleSection\":[\"F\u00e1brica de Niebla\",\"Sustentabilidade\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla\\\/\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla\\\/\",\"name\":\"M\u00e1s de 300 personas visitan la f\u00e1brica de Cementos Cosmos en Niebla | Votorantim Cimentos Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/visita-niebla.jpg\",\"datePublished\":\"2016-06-20T06:25:08+00:00\",\"dateModified\":\"2024-04-18T09:30:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/visita-niebla.jpg\",\"contentUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/visita-niebla.jpg\",\"width\":400,\"height\":300,\"caption\":\"Visitas a la f\u00e1brica de Niebla\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e1s de 300 personas visitan la f\u00e1brica de Cementos Cosmos en Niebla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/\",\"name\":\"Votorantim Cimentos Espa\u00f1a\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\",\"name\":\"teconsite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"caption\":\"teconsite\"},\"sameAs\":[\"https:\\\/\\\/www.votorantimcimentos.es\"],\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/author\\\/teconsite\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1s de 300 personas visitan la f\u00e1brica de Cementos Cosmos en Niebla | Votorantim Cimentos Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla\/","og_locale":"pt_PT","og_type":"article","og_title":"M\u00e1s de 300 personas visitan la f\u00e1brica de Cementos Cosmos en Niebla | Votorantim Cimentos Espa\u00f1a","og_description":"La f\u00e1brica de Cementos Cosmos de Niebla ha celebrado un d\u00eda de puertas abiertas, en el que m\u00e1s de 300 personas han podido disfrutar de una agradable jornada visitando las instalaciones.","og_url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla\/","og_site_name":"Votorantim Cimentos Espa\u00f1a","article_published_time":"2016-06-20T06:25:08+00:00","article_modified_time":"2024-04-18T09:30:11+00:00","og_image":[{"width":400,"height":300,"url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/visita-niebla.jpg","type":"image\/jpeg"}],"author":"teconsite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"teconsite","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla\/#article","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla\/"},"author":{"name":"teconsite","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d"},"headline":"M\u00e1s de 300 personas visitan la f\u00e1brica de Cementos Cosmos en Niebla","datePublished":"2016-06-20T06:25:08+00:00","dateModified":"2024-04-18T09:30:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla\/"},"wordCount":885,"image":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/visita-niebla.jpg","articleSection":["F\u00e1brica de Niebla","Sustentabilidade"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla\/","url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla\/","name":"M\u00e1s de 300 personas visitan la f\u00e1brica de Cementos Cosmos en Niebla | Votorantim Cimentos Espa\u00f1a","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla\/#primaryimage"},"image":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/visita-niebla.jpg","datePublished":"2016-06-20T06:25:08+00:00","dateModified":"2024-04-18T09:30:11+00:00","author":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d"},"breadcrumb":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla\/#primaryimage","url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/visita-niebla.jpg","contentUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/visita-niebla.jpg","width":400,"height":300,"caption":"Visitas a la f\u00e1brica de Niebla"},{"@type":"BreadcrumbList","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/mas-de-300-personas-visitan-la-fabrica-de-cementos-cosmos-en-niebla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.votorantimcimentos.es\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"M\u00e1s de 300 personas visitan la f\u00e1brica de Cementos Cosmos en Niebla"}]},{"@type":"WebSite","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#website","url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/","name":"Votorantim Cimentos Espa\u00f1a","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.votorantimcimentos.es\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d","name":"teconsite","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","caption":"teconsite"},"sameAs":["https:\/\/www.votorantimcimentos.es"],"url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/author\/teconsite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts\/26983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/comments?post=26983"}],"version-history":[{"count":1,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts\/26983\/revisions"}],"predecessor-version":[{"id":28363,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts\/26983\/revisions\/28363"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/media\/25687"}],"wp:attachment":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/media?parent=26983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/categories?post=26983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/tags?post=26983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}