{"id":26971,"date":"2016-10-07T08:25:08","date_gmt":"2016-10-07T06:25:08","guid":{"rendered":"https:\/\/www.votorantimcimentos.es\/noticias\/nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos\/"},"modified":"2024-04-18T11:30:00","modified_gmt":"2024-04-18T09:30:00","slug":"nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos","status":"publish","type":"post","link":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos\/","title":{"rendered":"Nueva donaci\u00f3n de sangre de los empleados de Cementos Cosmos"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>Toral de los Vados, 07 de octubre de 2016.- Los trabajadores de Cementos Cosmos se han sumado a una campa\u00f1a de donaci\u00f3n de sangre que ha tenido lugar en las instalaciones de la f\u00e1brica de cemento de Toral de los Vados. Se trata de la tercera edici\u00f3n de una iniciativa que arranc\u00f3 en julio de 2015 y que celebr\u00f3 su segunda convocatoria en febrero de este a\u00f1o.<\/p>\n<p>La jornada de donaci\u00f3n ha contado con la asistencia de 20 empleados interesados en colaborar con esta causa, que ha sido posible gracias a la cooperaci\u00f3n de la Hermandad de Donantes de Sangre del Bierzo y Laciana. El director de la f\u00e1brica, Jaime Santoalla, expres\u00f3 su gratitud a la Hermandad y a la plantilla por su involucraci\u00f3n, incidiendo en que \u201ces fundamental concienciar a la sociedad de que donar sangre es donar vida. En Cementos Cosmos estamos muy orgullosos de formar parte una vez m\u00e1s de esta iniciativa y seguimos trabajando para continuar promoviendo el esp\u00edritu solidario entre nuestros empleados\u201d.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La plantilla muestra su solidaridad sum\u00e1ndose por tercera vez a esta acci\u00f3n promovida por la Hermandad de Donantes de Sangre del Bierzo y Laciana<\/p>\n","protected":false},"author":1,"featured_media":25282,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[297,298],"tags":[],"class_list":["post-26971","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fabrica-de-toral-de-los-vados","category-sustentabilidade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nueva donaci\u00f3n de sangre de los empleados de Cementos Cosmos | Votorantim Cimentos Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nueva donaci\u00f3n de sangre de los empleados de Cementos Cosmos | Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"La plantilla muestra su solidaridad sum\u00e1ndose por tercera vez a esta acci\u00f3n promovida por la Hermandad de Donantes de Sangre del Bierzo y Laciana\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos\/\" \/>\n<meta property=\"og:site_name\" content=\"Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-07T06:25:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-18T09:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/690toral-donacionsangre-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1703\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"teconsite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"teconsite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos\\\/\"},\"author\":{\"name\":\"teconsite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\"},\"headline\":\"Nueva donaci\u00f3n de sangre de los empleados de Cementos Cosmos\",\"datePublished\":\"2016-10-07T06:25:08+00:00\",\"dateModified\":\"2024-04-18T09:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos\\\/\"},\"wordCount\":790,\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/690toral-donacionsangre-scaled.jpg\",\"articleSection\":[\"F\u00e1brica de Toral de los Vados\",\"Sustentabilidade\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos\\\/\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos\\\/\",\"name\":\"Nueva donaci\u00f3n de sangre de los empleados de Cementos Cosmos | Votorantim Cimentos Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/690toral-donacionsangre-scaled.jpg\",\"datePublished\":\"2016-10-07T06:25:08+00:00\",\"dateModified\":\"2024-04-18T09:30:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/690toral-donacionsangre-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/690toral-donacionsangre-scaled.jpg\",\"width\":2560,\"height\":1703,\"caption\":\"Donaci\u00f3n de sangre en Toral\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nueva donaci\u00f3n de sangre de los empleados de Cementos Cosmos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/\",\"name\":\"Votorantim Cimentos Espa\u00f1a\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\",\"name\":\"teconsite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"caption\":\"teconsite\"},\"sameAs\":[\"https:\\\/\\\/www.votorantimcimentos.es\"],\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/author\\\/teconsite\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nueva donaci\u00f3n de sangre de los empleados de Cementos Cosmos | Votorantim Cimentos Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos\/","og_locale":"pt_PT","og_type":"article","og_title":"Nueva donaci\u00f3n de sangre de los empleados de Cementos Cosmos | Votorantim Cimentos Espa\u00f1a","og_description":"La plantilla muestra su solidaridad sum\u00e1ndose por tercera vez a esta acci\u00f3n promovida por la Hermandad de Donantes de Sangre del Bierzo y Laciana","og_url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos\/","og_site_name":"Votorantim Cimentos Espa\u00f1a","article_published_time":"2016-10-07T06:25:08+00:00","article_modified_time":"2024-04-18T09:30:00+00:00","og_image":[{"width":2560,"height":1703,"url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/690toral-donacionsangre-scaled.jpg","type":"image\/jpeg"}],"author":"teconsite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"teconsite","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos\/#article","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos\/"},"author":{"name":"teconsite","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d"},"headline":"Nueva donaci\u00f3n de sangre de los empleados de Cementos Cosmos","datePublished":"2016-10-07T06:25:08+00:00","dateModified":"2024-04-18T09:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos\/"},"wordCount":790,"image":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/690toral-donacionsangre-scaled.jpg","articleSection":["F\u00e1brica de Toral de los Vados","Sustentabilidade"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos\/","url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos\/","name":"Nueva donaci\u00f3n de sangre de los empleados de Cementos Cosmos | Votorantim Cimentos Espa\u00f1a","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos\/#primaryimage"},"image":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/690toral-donacionsangre-scaled.jpg","datePublished":"2016-10-07T06:25:08+00:00","dateModified":"2024-04-18T09:30:00+00:00","author":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d"},"breadcrumb":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos\/#primaryimage","url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/690toral-donacionsangre-scaled.jpg","contentUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/690toral-donacionsangre-scaled.jpg","width":2560,"height":1703,"caption":"Donaci\u00f3n de sangre en Toral"},{"@type":"BreadcrumbList","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/nueva-donacion-de-sangre-de-los-empleados-de-cementos-cosmos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.votorantimcimentos.es\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Nueva donaci\u00f3n de sangre de los empleados de Cementos Cosmos"}]},{"@type":"WebSite","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#website","url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/","name":"Votorantim Cimentos Espa\u00f1a","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.votorantimcimentos.es\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d","name":"teconsite","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","caption":"teconsite"},"sameAs":["https:\/\/www.votorantimcimentos.es"],"url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/author\/teconsite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts\/26971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/comments?post=26971"}],"version-history":[{"count":1,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts\/26971\/revisions"}],"predecessor-version":[{"id":28349,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts\/26971\/revisions\/28349"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/media\/25282"}],"wp:attachment":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/media?parent=26971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/categories?post=26971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/tags?post=26971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}