{"id":26947,"date":"2017-05-04T08:25:08","date_gmt":"2017-05-04T06:25:08","guid":{"rendered":"https:\/\/www.votorantimcimentos.es\/noticias\/estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos\/"},"modified":"2024-04-18T11:29:18","modified_gmt":"2024-04-18T09:29:18","slug":"estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos","status":"publish","type":"post","link":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos\/","title":{"rendered":"Estudiantes del San Walabonso plantan \u00e1rboles en la cantera de Cementos Cosmos"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>Niebla, 4 de mayo de 2017.- La cantera de Cementos Cosmos en Niebla ha recibido la visita de 80 escolares procedentes del colegio San Walabonso, ubicado en el mismo municipio. Los estudiantes y sus educadores repoblaron una hect\u00e1rea de la explotaci\u00f3n con 240 \u00e1rboles de especies aut\u00f3ctonas, como algarrobos, encinas, alcornoques y acebuches. El evento se enmarca en la colaboraci\u00f3n entre la cementera y el centro educativo, a trav\u00e9s de un convenio que articula diversas iniciativas enfocadas a la mejora de la ense\u00f1anza de los alumnos.<\/p>\n<p>La actividad comenz\u00f3 hacia las 10:00 horas, con la llegada de los j\u00f3venes a la cantera y su distribuci\u00f3n en grupos. La plantaci\u00f3n se interrumpi\u00f3 hacia la mitad de la ma\u00f1ana para tomar un refrigerio y recuperar fuerzas. Culminada la labor y antes de volver al centro educativo, los ni\u00f1os y ni\u00f1as recibieron una insignia con el lema &#8216;Yo plant\u00e9 un \u00e1rbol para mi pueblo&#8217;. Con este obsequio, Cementos Cosmos les agradeci\u00f3 la participaci\u00f3n en un evento que se sit\u00faa en la estela de las celebraciones del D\u00eda Internacional de la Tierra. <\/p>\n<p>La insignia recuerda tambi\u00e9n que la plantaci\u00f3n de \u00e1rboles forma parte de la historia de Cementos Cosmos, que este a\u00f1o conmemora el 50 aniversario de la puesta en marcha la f\u00e1brica de Niebla. &#8220;La celebraci\u00f3n de esta efem\u00e9ride nos ha permitido contribuir a una actividad que beneficia doblemente a la comunidad, ya que refuerza la conciencia medioambiental de los escolares y contribuye tambi\u00e9n a mejorar el entorno natural&#8221;, ha explicado Jos\u00e9 de la Vega, director de la f\u00e1brica de Cementos Cosmos.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La cantera de Cementos Cosmos en Niebla ha recibido la visita de 80 escolares procedentes del colegio San Walabonso, ubicado en el mismo municipio. Los estudiantes y sus educadores repoblaron una hect\u00e1rea con 240 \u00e1rboles de especies aut\u00f3ctonas.<\/p>\n","protected":false},"author":1,"featured_media":25183,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[305,298],"tags":[],"class_list":["post-26947","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fabrica-de-niebla","category-sustentabilidade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estudiantes del San Walabonso plantan \u00e1rboles en la cantera de Cementos Cosmos | Votorantim Cimentos Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estudiantes del San Walabonso plantan \u00e1rboles en la cantera de Cementos Cosmos | Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"La cantera de Cementos Cosmos en Niebla ha recibido la visita de 80 escolares procedentes del colegio San Walabonso, ubicado en el mismo municipio. Los estudiantes y sus educadores repoblaron una hect\u00e1rea con 240 \u00e1rboles de especies aut\u00f3ctonas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos\/\" \/>\n<meta property=\"og:site_name\" content=\"Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-04T06:25:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-18T09:29:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/170504-reforestacion.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"teconsite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"teconsite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos\\\/\"},\"author\":{\"name\":\"teconsite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\"},\"headline\":\"Estudiantes del San Walabonso plantan \u00e1rboles en la cantera de Cementos Cosmos\",\"datePublished\":\"2017-05-04T06:25:08+00:00\",\"dateModified\":\"2024-04-18T09:29:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos\\\/\"},\"wordCount\":893,\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/170504-reforestacion.jpg\",\"articleSection\":[\"F\u00e1brica de Niebla\",\"Sustentabilidade\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos\\\/\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos\\\/\",\"name\":\"Estudiantes del San Walabonso plantan \u00e1rboles en la cantera de Cementos Cosmos | Votorantim Cimentos Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/170504-reforestacion.jpg\",\"datePublished\":\"2017-05-04T06:25:08+00:00\",\"dateModified\":\"2024-04-18T09:29:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/170504-reforestacion.jpg\",\"contentUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/170504-reforestacion.jpg\",\"width\":1000,\"height\":750,\"caption\":\"Reforestaci\u00f3n por Votorantim Cimentos Espa\u00f1a\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estudiantes del San Walabonso plantan \u00e1rboles en la cantera de Cementos Cosmos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/\",\"name\":\"Votorantim Cimentos Espa\u00f1a\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\",\"name\":\"teconsite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"caption\":\"teconsite\"},\"sameAs\":[\"https:\\\/\\\/www.votorantimcimentos.es\"],\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/author\\\/teconsite\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estudiantes del San Walabonso plantan \u00e1rboles en la cantera de Cementos Cosmos | Votorantim Cimentos Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos\/","og_locale":"pt_PT","og_type":"article","og_title":"Estudiantes del San Walabonso plantan \u00e1rboles en la cantera de Cementos Cosmos | Votorantim Cimentos Espa\u00f1a","og_description":"La cantera de Cementos Cosmos en Niebla ha recibido la visita de 80 escolares procedentes del colegio San Walabonso, ubicado en el mismo municipio. Los estudiantes y sus educadores repoblaron una hect\u00e1rea con 240 \u00e1rboles de especies aut\u00f3ctonas.","og_url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos\/","og_site_name":"Votorantim Cimentos Espa\u00f1a","article_published_time":"2017-05-04T06:25:08+00:00","article_modified_time":"2024-04-18T09:29:18+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/170504-reforestacion.jpg","type":"image\/jpeg"}],"author":"teconsite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"teconsite","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos\/#article","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos\/"},"author":{"name":"teconsite","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d"},"headline":"Estudiantes del San Walabonso plantan \u00e1rboles en la cantera de Cementos Cosmos","datePublished":"2017-05-04T06:25:08+00:00","dateModified":"2024-04-18T09:29:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos\/"},"wordCount":893,"image":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/170504-reforestacion.jpg","articleSection":["F\u00e1brica de Niebla","Sustentabilidade"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos\/","url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos\/","name":"Estudiantes del San Walabonso plantan \u00e1rboles en la cantera de Cementos Cosmos | Votorantim Cimentos Espa\u00f1a","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos\/#primaryimage"},"image":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/170504-reforestacion.jpg","datePublished":"2017-05-04T06:25:08+00:00","dateModified":"2024-04-18T09:29:18+00:00","author":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d"},"breadcrumb":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos\/#primaryimage","url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/170504-reforestacion.jpg","contentUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/170504-reforestacion.jpg","width":1000,"height":750,"caption":"Reforestaci\u00f3n por Votorantim Cimentos Espa\u00f1a"},{"@type":"BreadcrumbList","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/estudiantes-del-san-walabonso-plantan-arboles-en-la-cantera-de-cementos-cosmos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.votorantimcimentos.es\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Estudiantes del San Walabonso plantan \u00e1rboles en la cantera de Cementos Cosmos"}]},{"@type":"WebSite","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#website","url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/","name":"Votorantim Cimentos Espa\u00f1a","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.votorantimcimentos.es\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d","name":"teconsite","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","caption":"teconsite"},"sameAs":["https:\/\/www.votorantimcimentos.es"],"url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/author\/teconsite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts\/26947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/comments?post=26947"}],"version-history":[{"count":1,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts\/26947\/revisions"}],"predecessor-version":[{"id":28325,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts\/26947\/revisions\/28325"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/media\/25183"}],"wp:attachment":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/media?parent=26947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/categories?post=26947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/tags?post=26947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}