{"id":26938,"date":"2017-10-30T08:25:08","date_gmt":"2017-10-30T07:25:08","guid":{"rendered":"https:\/\/www.votorantimcimentos.es\/noticias\/empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul\/"},"modified":"2024-04-18T11:29:13","modified_gmt":"2024-04-18T09:29:13","slug":"empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul","status":"publish","type":"post","link":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul\/","title":{"rendered":"Empleados y familiares de Cementos Cosmos colaboran en la limpieza del Lago Azul"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>C\u00f3rdoba, 30 de octubre de 2017.- Trabajadores de Cementos Cosmos, acompa\u00f1ados por sus familiares, han participado en una actividad de limpieza del entorno del Lago Azul. La iniciativa, surgida de la colaboraci\u00f3n entre la ONG Gea y la cementera, cont\u00f3 con la intervenci\u00f3n de unos 30 voluntarios que aportaron su tiempo y esfuerzos para mejorar un espacio de gran valor ecol\u00f3gico situado en los terrenos de la empresa.<\/p>\n<p>El Lago Azul, llamado popularmente as\u00ed por el color turquesa de sus aguas, se form\u00f3 hace varias d\u00e9cadas en una zona restaurada de la cantera que se hab\u00eda dejado de explotar. En la actualidad, con una extensi\u00f3n de 12 hect\u00e1reas, cuenta con agua todo el a\u00f1o debido a que se encuentra por debajo del nivel fre\u00e1tico y a las aportaciones de escorrent\u00eda de los arroyos pr\u00f3ximos durante el invierno.<\/p>\n<p>Pese a su elevado valor ecol\u00f3gico y paisaj\u00edstico, en algunas partes de la charca se encuentran desperdicios que abandonan los visitantes furtivos, aunque el acceso a la zona est\u00e1 restringido por motivos de seguridad y de protecci\u00f3n ambiental. &#8220;Cementos Cosmos est\u00e1 muy agradecida a la ONG por su apoyo en el mantenimiento y reivindicaci\u00f3n de un bien natural en cuya conservaci\u00f3n estamos muy comprometidos&#8221;, ha afirmado Jos\u00e9 de la Vega, director de la cementera.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Trabajadores de Cosmos, acompa\u00f1ados por sus familiares, han participado en una actividad de limpieza del entorno del Lago Azul. La iniciativa, surgida de la colaboraci\u00f3n entre la ONG Gea y la cementera, cont\u00f3 con la intervenci\u00f3n de unos 30 voluntarios.<\/p>\n","protected":false},"author":1,"featured_media":25146,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[304,298],"tags":[],"class_list":["post-26938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fabrica-de-cordova","category-sustentabilidade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Empleados y familiares de Cementos Cosmos colaboran en la limpieza del Lago Azul | Votorantim Cimentos Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Empleados y familiares de Cementos Cosmos colaboran en la limpieza del Lago Azul | Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"Trabajadores de Cosmos, acompa\u00f1ados por sus familiares, han participado en una actividad de limpieza del entorno del Lago Azul. La iniciativa, surgida de la colaboraci\u00f3n entre la ONG Gea y la cementera, cont\u00f3 con la intervenci\u00f3n de unos 30 voluntarios.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul\/\" \/>\n<meta property=\"og:site_name\" content=\"Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-30T07:25:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-18T09:29:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/cosmos-y-gea-lago-azul.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"teconsite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"teconsite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul\\\/\"},\"author\":{\"name\":\"teconsite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\"},\"headline\":\"Empleados y familiares de Cementos Cosmos colaboran en la limpieza del Lago Azul\",\"datePublished\":\"2017-10-30T07:25:08+00:00\",\"dateModified\":\"2024-04-18T09:29:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul\\\/\"},\"wordCount\":843,\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cosmos-y-gea-lago-azul.jpg\",\"articleSection\":[\"F\u00e1brica de C\u00f3rdova\",\"Sustentabilidade\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul\\\/\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul\\\/\",\"name\":\"Empleados y familiares de Cementos Cosmos colaboran en la limpieza del Lago Azul | Votorantim Cimentos Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cosmos-y-gea-lago-azul.jpg\",\"datePublished\":\"2017-10-30T07:25:08+00:00\",\"dateModified\":\"2024-04-18T09:29:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cosmos-y-gea-lago-azul.jpg\",\"contentUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cosmos-y-gea-lago-azul.jpg\",\"width\":1000,\"height\":750,\"caption\":\"Cosmos y GEA, Lago Azul\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empleados y familiares de Cementos Cosmos colaboran en la limpieza del Lago Azul\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/\",\"name\":\"Votorantim Cimentos Espa\u00f1a\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\",\"name\":\"teconsite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"caption\":\"teconsite\"},\"sameAs\":[\"https:\\\/\\\/www.votorantimcimentos.es\"],\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/author\\\/teconsite\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Empleados y familiares de Cementos Cosmos colaboran en la limpieza del Lago Azul | Votorantim Cimentos Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul\/","og_locale":"pt_PT","og_type":"article","og_title":"Empleados y familiares de Cementos Cosmos colaboran en la limpieza del Lago Azul | Votorantim Cimentos Espa\u00f1a","og_description":"Trabajadores de Cosmos, acompa\u00f1ados por sus familiares, han participado en una actividad de limpieza del entorno del Lago Azul. La iniciativa, surgida de la colaboraci\u00f3n entre la ONG Gea y la cementera, cont\u00f3 con la intervenci\u00f3n de unos 30 voluntarios.","og_url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul\/","og_site_name":"Votorantim Cimentos Espa\u00f1a","article_published_time":"2017-10-30T07:25:08+00:00","article_modified_time":"2024-04-18T09:29:13+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/cosmos-y-gea-lago-azul.jpg","type":"image\/jpeg"}],"author":"teconsite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"teconsite","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul\/#article","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul\/"},"author":{"name":"teconsite","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d"},"headline":"Empleados y familiares de Cementos Cosmos colaboran en la limpieza del Lago Azul","datePublished":"2017-10-30T07:25:08+00:00","dateModified":"2024-04-18T09:29:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul\/"},"wordCount":843,"image":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/cosmos-y-gea-lago-azul.jpg","articleSection":["F\u00e1brica de C\u00f3rdova","Sustentabilidade"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul\/","url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul\/","name":"Empleados y familiares de Cementos Cosmos colaboran en la limpieza del Lago Azul | Votorantim Cimentos Espa\u00f1a","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul\/#primaryimage"},"image":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/cosmos-y-gea-lago-azul.jpg","datePublished":"2017-10-30T07:25:08+00:00","dateModified":"2024-04-18T09:29:13+00:00","author":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d"},"breadcrumb":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul\/#primaryimage","url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/cosmos-y-gea-lago-azul.jpg","contentUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/cosmos-y-gea-lago-azul.jpg","width":1000,"height":750,"caption":"Cosmos y GEA, Lago Azul"},{"@type":"BreadcrumbList","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/empleados-y-familiares-de-cementos-cosmos-colaboran-en-la-limpieza-del-lago-azul\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.votorantimcimentos.es\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Empleados y familiares de Cementos Cosmos colaboran en la limpieza del Lago Azul"}]},{"@type":"WebSite","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#website","url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/","name":"Votorantim Cimentos Espa\u00f1a","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.votorantimcimentos.es\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d","name":"teconsite","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","caption":"teconsite"},"sameAs":["https:\/\/www.votorantimcimentos.es"],"url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/author\/teconsite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts\/26938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/comments?post=26938"}],"version-history":[{"count":1,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts\/26938\/revisions"}],"predecessor-version":[{"id":28316,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts\/26938\/revisions\/28316"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/media\/25146"}],"wp:attachment":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/media?parent=26938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/categories?post=26938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/tags?post=26938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}