{"id":26810,"date":"2023-01-17T16:28:12","date_gmt":"2023-01-17T15:28:12","guid":{"rendered":"https:\/\/www.votorantimcimentos.es\/noticias\/votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana\/"},"modified":"2024-04-18T11:23:58","modified_gmt":"2024-04-18T09:23:58","slug":"votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana","status":"publish","type":"post","link":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana\/","title":{"rendered":"Votorantim Cimentos renueva el reconocimiento de Top Employer en Espa\u00f1a"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p><b><i>Madrid<\/i>, 17 de enero de 2023 &#8211;<\/b> Votorantim Cimentos ha renovado el reconocimiento de empresa Top Employer, lo que la acredita como una organizaci\u00f3n l\u00edder en las pol\u00edticas de personas y un buen lugar para trabajar. Esto incluye todos los centros de producci\u00f3n del grupo en Espa\u00f1a, as\u00ed como las sedes de Votorantim Cimentos Espa\u00f1a y la corporativa de la regi\u00f3n Votorantim Cimentos Europa, \u00c1frica y Asia.<\/p>\n<p>Por segundo a\u00f1o consecutivo, Votorantim Cimentos ha superado un proceso de an\u00e1lisis y evaluaci\u00f3n de todas las \u00e1reas fundamentales de gesti\u00f3n de recursos humanos, tales como la Estrategia de Personas, Ambiente de Trabajo, Adquisici\u00f3n de Talento, Aprendizaje, Bienestar y Diversidad e Inclusi\u00f3n, entre otros.<\/p>\n<p>En este an\u00e1lisis, que ha durado nueve meses, la empresa cementera ha destacado especialmente en las \u00e1reas de Valores, Bienestar, Diversidad e Inclusi\u00f3n y Sostenibilidad. En este sentido, Votorantim Cimentos cuenta con los sellos \u201cDiversity Leading Company\u201d que certifica su compromiso como empresa l\u00edder en diversidad, equidad e inclusi\u00f3n, y \u201cEmpowering Women\u00b4s Talent\u201d, reconociendo el esfuerzo de la empresa por impulsar el talento y liderazgo femeninos. Adem\u00e1s, ha obtenido varios premios y reconocimientos que avalan su estrategia y buen hacer en materia de Bienestar y Salud. El m\u00e1s reciente, el Premio Prevencionar como reconocimiento a la defensa, est\u00edmulo y apoyo en el campo de la salud, seguridad y bienestar en el trabajo. Asimismo, cuenta con el reconocimiento de Empresa Saludable y Sostenible en Promoci\u00f3n de la Salud en el Trabajo otorgado por el Instituto Nacional de Seguridad y Salud en el Trabajo (Ministerio de Trabajo). Dicho reconocimiento, el mayor a nivel oficial en nuestro pa\u00eds en esta materia, pone en valor el trabajo de las empresas en el \u00e1mbito de la mejora de la salud y el bienestar de sus trabajadores, as\u00ed como en la promoci\u00f3n de la cultura de la salud.<\/p>\n<p>Alberto Carrillo, director de Personas de Votorantim Cimentos, ha declarado sobre la renovaci\u00f3n de este certificado: \u201cLas personas constituyen uno de los ejes estrat\u00e9gicos de la compa\u00f1\u00eda. El bienestar, la salud y la seguridad de la plantilla, la comunicaci\u00f3n fluida con el equipo, el respeto por la diversidad y la inclusi\u00f3n, y el impulso a la formaci\u00f3n, la solidaridad y la sostenibilidad son las m\u00e1ximas que gu\u00edan el comportamiento de Votorantim Cimentos\u201d.<\/p>\n<p>David Plink, CEO de Top Employers Institute afirm\u00f3: \u201cAdapt\u00e1ndose a los retos y exigencias de este a\u00f1o que, al igual que en el a\u00f1o anterior, han impactado en las organizaciones de todo el mundo, Votorantim Cimentos ha continuado demostrando que prioriza la implementaci\u00f3n de excelentes pr\u00e1cticas de personas en el lugar de trabajo. Las compa\u00f1\u00edas Top Employer contin\u00faan enfrent\u00e1ndose a los desaf\u00edos que plantea un mundo del trabajo en continuo cambio mientras trabajan incansablemente para lograr un impacto positivo en la vida de sus colaboradores.\u201d<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Esto incluye todos los centros de producci\u00f3n del grupo en Espa\u00f1a, as\u00ed como las sedes de Votorantim Cimentos Espa\u00f1a y la corporativa de la regi\u00f3n Votorantim Cimentos Europa, \u00c1frica y Asia.<\/p>\n","protected":false},"author":2,"featured_media":24042,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311,309,303,304,302,305,306,297,310,307,300,298],"tags":[],"class_list":["post-26810","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-argamassa","category-betao","category-fabrica-de-alconera","category-fabrica-de-cordova","category-fabrica-de-malaga","category-fabrica-de-niebla","category-fabrica-de-oural","category-fabrica-de-toral-de-los-vados","category-moagem-de-bobadilla","category-moagem-de-tenerife","category-premios-e-reconhecimentos","category-sustentabilidade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Votorantim Cimentos renueva el reconocimiento de Top Employer en Espa\u00f1a | Votorantim Cimentos Espa\u00f1a<\/title>\n<meta name=\"description\" content=\"Esto incluye todos los centros de producci\u00f3n del grupo en Espa\u00f1a, as\u00ed como las sedes de Votorantim Cimentos Espa\u00f1a y la corporativa de la regi\u00f3n Votorantim Cimentos Europa, \u00c1frica y Asia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Votorantim Cimentos renueva el reconocimiento de Top Employer en Espa\u00f1a | Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"Esto incluye todos los centros de producci\u00f3n del grupo en Espa\u00f1a, as\u00ed como las sedes de Votorantim Cimentos Espa\u00f1a y la corporativa de la regi\u00f3n Votorantim Cimentos Europa, \u00c1frica y Asia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana\/\" \/>\n<meta property=\"og:site_name\" content=\"Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-17T15:28:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-18T09:23:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/11\/fabrica-niebla-e1701271666960.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"691\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Votorantim Cimentos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Votorantim Cimentos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana\\\/\"},\"author\":{\"name\":\"Votorantim Cimentos\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#\\\/schema\\\/person\\\/4de32fe180e055b1d423bbdfa28b3044\"},\"headline\":\"Votorantim Cimentos renueva el reconocimiento de Top Employer en Espa\u00f1a\",\"datePublished\":\"2023-01-17T15:28:12+00:00\",\"dateModified\":\"2024-04-18T09:23:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana\\\/\"},\"wordCount\":979,\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/fabrica-niebla-e1701271666960.jpg\",\"articleSection\":[\"Argamassa\",\"Bet\u00e3o\",\"F\u00e1brica de Alconera\",\"F\u00e1brica de C\u00f3rdova\",\"F\u00e1brica de M\u00e1laga\",\"F\u00e1brica de Niebla\",\"F\u00e1brica de Oural\",\"F\u00e1brica de Toral de los Vados\",\"Moagem de Bobadilla\",\"Moagem de Tenerife\",\"Pr\u00e9mios e Reconhecimentos\",\"Sustentabilidade\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana\\\/\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana\\\/\",\"name\":\"Votorantim Cimentos renueva el reconocimiento de Top Employer en Espa\u00f1a | Votorantim Cimentos Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/fabrica-niebla-e1701271666960.jpg\",\"datePublished\":\"2023-01-17T15:28:12+00:00\",\"dateModified\":\"2024-04-18T09:23:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#\\\/schema\\\/person\\\/4de32fe180e055b1d423bbdfa28b3044\"},\"description\":\"Esto incluye todos los centros de producci\u00f3n del grupo en Espa\u00f1a, as\u00ed como las sedes de Votorantim Cimentos Espa\u00f1a y la corporativa de la regi\u00f3n Votorantim Cimentos Europa, \u00c1frica y Asia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/fabrica-niebla-e1701271666960.jpg\",\"contentUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/fabrica-niebla-e1701271666960.jpg\",\"width\":1000,\"height\":691},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Votorantim Cimentos renueva el reconocimiento de Top Employer en Espa\u00f1a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/\",\"name\":\"Votorantim Cimentos Espa\u00f1a\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#\\\/schema\\\/person\\\/4de32fe180e055b1d423bbdfa28b3044\",\"name\":\"Votorantim Cimentos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6df14fcca736e04ee8aeb4a1c51fd540d783a0ceb50876d491e877a532c0c3e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6df14fcca736e04ee8aeb4a1c51fd540d783a0ceb50876d491e877a532c0c3e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6df14fcca736e04ee8aeb4a1c51fd540d783a0ceb50876d491e877a532c0c3e?s=96&d=mm&r=g\",\"caption\":\"Votorantim Cimentos\"},\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/author\\\/votorantim\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Votorantim Cimentos renueva el reconocimiento de Top Employer en Espa\u00f1a | Votorantim Cimentos Espa\u00f1a","description":"Esto incluye todos los centros de producci\u00f3n del grupo en Espa\u00f1a, as\u00ed como las sedes de Votorantim Cimentos Espa\u00f1a y la corporativa de la regi\u00f3n Votorantim Cimentos Europa, \u00c1frica y Asia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana\/","og_locale":"pt_PT","og_type":"article","og_title":"Votorantim Cimentos renueva el reconocimiento de Top Employer en Espa\u00f1a | Votorantim Cimentos Espa\u00f1a","og_description":"Esto incluye todos los centros de producci\u00f3n del grupo en Espa\u00f1a, as\u00ed como las sedes de Votorantim Cimentos Espa\u00f1a y la corporativa de la regi\u00f3n Votorantim Cimentos Europa, \u00c1frica y Asia.","og_url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana\/","og_site_name":"Votorantim Cimentos Espa\u00f1a","article_published_time":"2023-01-17T15:28:12+00:00","article_modified_time":"2024-04-18T09:23:58+00:00","og_image":[{"width":1000,"height":691,"url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/11\/fabrica-niebla-e1701271666960.jpg","type":"image\/jpeg"}],"author":"Votorantim Cimentos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Votorantim Cimentos","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana\/#article","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana\/"},"author":{"name":"Votorantim Cimentos","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#\/schema\/person\/4de32fe180e055b1d423bbdfa28b3044"},"headline":"Votorantim Cimentos renueva el reconocimiento de Top Employer en Espa\u00f1a","datePublished":"2023-01-17T15:28:12+00:00","dateModified":"2024-04-18T09:23:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana\/"},"wordCount":979,"image":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/11\/fabrica-niebla-e1701271666960.jpg","articleSection":["Argamassa","Bet\u00e3o","F\u00e1brica de Alconera","F\u00e1brica de C\u00f3rdova","F\u00e1brica de M\u00e1laga","F\u00e1brica de Niebla","F\u00e1brica de Oural","F\u00e1brica de Toral de los Vados","Moagem de Bobadilla","Moagem de Tenerife","Pr\u00e9mios e Reconhecimentos","Sustentabilidade"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana\/","url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana\/","name":"Votorantim Cimentos renueva el reconocimiento de Top Employer en Espa\u00f1a | Votorantim Cimentos Espa\u00f1a","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana\/#primaryimage"},"image":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/11\/fabrica-niebla-e1701271666960.jpg","datePublished":"2023-01-17T15:28:12+00:00","dateModified":"2024-04-18T09:23:58+00:00","author":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#\/schema\/person\/4de32fe180e055b1d423bbdfa28b3044"},"description":"Esto incluye todos los centros de producci\u00f3n del grupo en Espa\u00f1a, as\u00ed como las sedes de Votorantim Cimentos Espa\u00f1a y la corporativa de la regi\u00f3n Votorantim Cimentos Europa, \u00c1frica y Asia.","breadcrumb":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana\/#primaryimage","url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/11\/fabrica-niebla-e1701271666960.jpg","contentUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/11\/fabrica-niebla-e1701271666960.jpg","width":1000,"height":691},{"@type":"BreadcrumbList","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/votorantim-cimentos-renueva-el-reconocimiento-de-top-employer-en-espana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.votorantimcimentos.es\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Votorantim Cimentos renueva el reconocimiento de Top Employer en Espa\u00f1a"}]},{"@type":"WebSite","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#website","url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/","name":"Votorantim Cimentos Espa\u00f1a","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.votorantimcimentos.es\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#\/schema\/person\/4de32fe180e055b1d423bbdfa28b3044","name":"Votorantim Cimentos","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/a6df14fcca736e04ee8aeb4a1c51fd540d783a0ceb50876d491e877a532c0c3e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a6df14fcca736e04ee8aeb4a1c51fd540d783a0ceb50876d491e877a532c0c3e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a6df14fcca736e04ee8aeb4a1c51fd540d783a0ceb50876d491e877a532c0c3e?s=96&d=mm&r=g","caption":"Votorantim Cimentos"},"url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/author\/votorantim\/"}]}},"_links":{"self":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts\/26810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/comments?post=26810"}],"version-history":[{"count":1,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts\/26810\/revisions"}],"predecessor-version":[{"id":28190,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts\/26810\/revisions\/28190"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/media\/24042"}],"wp:attachment":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/media?parent=26810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/categories?post=26810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/tags?post=26810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}