{"id":26781,"date":"2023-11-13T09:52:29","date_gmt":"2023-11-13T08:52:29","guid":{"rendered":"https:\/\/www.votorantimcimentos.es\/noticias\/alconera-plan-biodiversidad\/"},"modified":"2024-04-18T11:22:56","modified_gmt":"2024-04-18T09:22:56","slug":"alconera-plan-biodiversidad","status":"publish","type":"post","link":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/alconera-plan-biodiversidad\/","title":{"rendered":"La f\u00e1brica de Alconera aborda las primeras acciones de su plan de gesti\u00f3n de la biodiversidad"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p><em><strong>Alconera,<\/strong><\/em> <strong>13 de noviembre de<\/strong> <strong>2023 &#8211;<\/strong> La cantera de pizarra de la f\u00e1brica de cemento de Alconera ha sido el lugar elegido para llevar a cabo las primeras actuaciones del plan de gesti\u00f3n de la biodiversidad de la empresa.<\/p>\n<p>Tras analizar durante seis meses los h\u00e1bitats existentes y potenciales en los terrenos de la cementera y realizar un inventario de la fauna y flora se han plantado de forma experimental dos tipos de \u00e1rboles de crecimiento lento t\u00edpicos de la dehesa, encinas y alcornoques. Los plantones cuentan con sistema de protecci\u00f3n frente al ganado que pasta en la zona, para ver la efectividad de las protecciones para futuras repoblaciones.<\/p>\n<p>Adem\u00e1s, se ha instalado un sistema de captaci\u00f3n y aprovechamiento de agua, denominado Waterboxx. Este m\u00e9todo es mucho m\u00e1s eficiente que el riego por goteo y aumenta la supervivencia de los plantones. Tan solo en el primer a\u00f1o, el Waterboxx permite ahorrar hasta un 90% de agua respecto a los sistemas de riego tradicionales. Por otro lado, confirma la respuesta de las dos especies, con necesidades h\u00eddricas distintas, as\u00ed como su adaptaci\u00f3n.<\/p>\n<p>Votorantim Cimentos, propietaria de la planta de Alconera, est\u00e1 realizando este plan de gesti\u00f3n de la Biodiversidad con Fundaci\u00f3n Tormes-EB, entidad con gran experiencia en esta materia.<\/p>\n<p>La Fundaci\u00f3n Tormes gestiona desde hace m\u00e1s de cinco a\u00f1os el plan de biodiversidad de otras instalaciones de Votorantim Cimentos. Concretamente de la f\u00e1brica de cemento de M\u00e1laga y de la cantera de La Utrera, en la misma provincia. En esos proyectos se trabaja en m\u00e1s de 250 hect\u00e1reas enfocadas a la compatibilizaci\u00f3n del proceso productivo con la conservaci\u00f3n y mejora de h\u00e1bitats end\u00e9micos de alto valor, as\u00ed como en novedosas t\u00e9cnicas de restauraci\u00f3n integral.<\/p>\n<p>Seg\u00fan Pablo Viedma, director de la f\u00e1brica de Alconera: &#8220;Apostamos por garantizar la conservaci\u00f3n, mejora y puesta en valor de la riqueza natural de nuestros terrenos industriales y el mejor instrumento para llevarlo a cabo es la implantaci\u00f3n de planes de gesti\u00f3n de la biodiversidad. Estas actuaciones que acabamos de poner en marcha son el inicio de un largo camino que confirma la compatibilidad de la producci\u00f3n de cemento con la protecci\u00f3n del medio natural y de los ecosistemas locales&#8221;.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La cantera de pizarra de la f\u00e1brica de cemento de Alconera ha sido el lugar elegido para llevar a cabo las primeras actuaciones del plan de gesti\u00f3n de la biodiversidad.<\/p>\n","protected":false},"author":1,"featured_media":23997,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[303,298],"tags":[299],"class_list":["post-26781","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fabrica-de-alconera","category-sustentabilidade","tag-cemento-pt-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La f\u00e1brica de Alconera aborda las primeras acciones de su plan de gesti\u00f3n de la biodiversidad | Votorantim Cimentos Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/alconera-plan-biodiversidad\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La f\u00e1brica de Alconera aborda las primeras acciones de su plan de gesti\u00f3n de la biodiversidad | Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"La cantera de pizarra de la f\u00e1brica de cemento de Alconera ha sido el lugar elegido para llevar a cabo las primeras actuaciones del plan de gesti\u00f3n de la biodiversidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/alconera-plan-biodiversidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-13T08:52:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-18T09:22:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/11\/231113-Biodiversidad-Alconera-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1180\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"teconsite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"teconsite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/alconera-plan-biodiversidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/alconera-plan-biodiversidad\\\/\"},\"author\":{\"name\":\"teconsite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\"},\"headline\":\"La f\u00e1brica de Alconera aborda las primeras acciones de su plan de gesti\u00f3n de la biodiversidad\",\"datePublished\":\"2023-11-13T08:52:29+00:00\",\"dateModified\":\"2024-04-18T09:22:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/alconera-plan-biodiversidad\\\/\"},\"wordCount\":1082,\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/alconera-plan-biodiversidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/231113-Biodiversidad-Alconera-scaled.jpg\",\"keywords\":[\"Cemento\"],\"articleSection\":[\"F\u00e1brica de Alconera\",\"Sustentabilidade\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/alconera-plan-biodiversidad\\\/\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/alconera-plan-biodiversidad\\\/\",\"name\":\"La f\u00e1brica de Alconera aborda las primeras acciones de su plan de gesti\u00f3n de la biodiversidad | Votorantim Cimentos Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/alconera-plan-biodiversidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/alconera-plan-biodiversidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/231113-Biodiversidad-Alconera-scaled.jpg\",\"datePublished\":\"2023-11-13T08:52:29+00:00\",\"dateModified\":\"2024-04-18T09:22:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/alconera-plan-biodiversidad\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/alconera-plan-biodiversidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/alconera-plan-biodiversidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/231113-Biodiversidad-Alconera-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/231113-Biodiversidad-Alconera-scaled.jpg\",\"width\":2560,\"height\":1180},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/alconera-plan-biodiversidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La f\u00e1brica de Alconera aborda las primeras acciones de su plan de gesti\u00f3n de la biodiversidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/\",\"name\":\"Votorantim Cimentos Espa\u00f1a\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\",\"name\":\"teconsite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"caption\":\"teconsite\"},\"sameAs\":[\"https:\\\/\\\/www.votorantimcimentos.es\"],\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/pt-pt\\\/noticias\\\/author\\\/teconsite\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La f\u00e1brica de Alconera aborda las primeras acciones de su plan de gesti\u00f3n de la biodiversidad | Votorantim Cimentos Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/alconera-plan-biodiversidad\/","og_locale":"pt_PT","og_type":"article","og_title":"La f\u00e1brica de Alconera aborda las primeras acciones de su plan de gesti\u00f3n de la biodiversidad | Votorantim Cimentos Espa\u00f1a","og_description":"La cantera de pizarra de la f\u00e1brica de cemento de Alconera ha sido el lugar elegido para llevar a cabo las primeras actuaciones del plan de gesti\u00f3n de la biodiversidad.","og_url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/alconera-plan-biodiversidad\/","og_site_name":"Votorantim Cimentos Espa\u00f1a","article_published_time":"2023-11-13T08:52:29+00:00","article_modified_time":"2024-04-18T09:22:56+00:00","og_image":[{"width":2560,"height":1180,"url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/11\/231113-Biodiversidad-Alconera-scaled.jpg","type":"image\/jpeg"}],"author":"teconsite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"teconsite","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/alconera-plan-biodiversidad\/#article","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/alconera-plan-biodiversidad\/"},"author":{"name":"teconsite","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d"},"headline":"La f\u00e1brica de Alconera aborda las primeras acciones de su plan de gesti\u00f3n de la biodiversidad","datePublished":"2023-11-13T08:52:29+00:00","dateModified":"2024-04-18T09:22:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/alconera-plan-biodiversidad\/"},"wordCount":1082,"image":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/alconera-plan-biodiversidad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/11\/231113-Biodiversidad-Alconera-scaled.jpg","keywords":["Cemento"],"articleSection":["F\u00e1brica de Alconera","Sustentabilidade"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/alconera-plan-biodiversidad\/","url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/alconera-plan-biodiversidad\/","name":"La f\u00e1brica de Alconera aborda las primeras acciones de su plan de gesti\u00f3n de la biodiversidad | Votorantim Cimentos Espa\u00f1a","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/alconera-plan-biodiversidad\/#primaryimage"},"image":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/alconera-plan-biodiversidad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/11\/231113-Biodiversidad-Alconera-scaled.jpg","datePublished":"2023-11-13T08:52:29+00:00","dateModified":"2024-04-18T09:22:56+00:00","author":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d"},"breadcrumb":{"@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/alconera-plan-biodiversidad\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/alconera-plan-biodiversidad\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/alconera-plan-biodiversidad\/#primaryimage","url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/11\/231113-Biodiversidad-Alconera-scaled.jpg","contentUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/11\/231113-Biodiversidad-Alconera-scaled.jpg","width":2560,"height":1180},{"@type":"BreadcrumbList","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/alconera-plan-biodiversidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.votorantimcimentos.es\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"La f\u00e1brica de Alconera aborda las primeras acciones de su plan de gesti\u00f3n de la biodiversidad"}]},{"@type":"WebSite","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#website","url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/","name":"Votorantim Cimentos Espa\u00f1a","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.votorantimcimentos.es\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/www.votorantimcimentos.es\/pt-pt\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d","name":"teconsite","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","caption":"teconsite"},"sameAs":["https:\/\/www.votorantimcimentos.es"],"url":"https:\/\/www.votorantimcimentos.es\/pt-pt\/noticias\/author\/teconsite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts\/26781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/comments?post=26781"}],"version-history":[{"count":1,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts\/26781\/revisions"}],"predecessor-version":[{"id":28161,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/posts\/26781\/revisions\/28161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/media\/23997"}],"wp:attachment":[{"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/media?parent=26781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/categories?post=26781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/pt-pt\/wp-json\/wp\/v2\/tags?post=26781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}