{"id":32036,"date":"2026-07-03T09:42:44","date_gmt":"2026-07-03T07:42:44","guid":{"rendered":"https:\/\/www.votorantimcimentos.es\/?p=32036"},"modified":"2026-07-03T09:42:44","modified_gmt":"2026-07-03T07:42:44","slug":"la-fabrica-de-toral-celebra-una-jornada-deportiva-inclusiva-con-asprona-bierzo-y-el-atleta-adnan-almousa-alfermli","status":"publish","type":"post","link":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-toral-celebra-una-jornada-deportiva-inclusiva-con-asprona-bierzo-y-el-atleta-adnan-almousa-alfermli\/","title":{"rendered":"La f\u00e1brica de Toral celebra una jornada deportiva inclusiva con Asprona Bierzo y el atleta Adnan Almousa Alfermli"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p><b><i>Toral de los Vados<\/i>, 3 de julio de 2026.-<\/b> La f\u00e1brica de cemento de Toral de los Vados ha acogido una jornada de deporte inclusivo en colaboraci\u00f3n con Asprona Bierzo, en la que han participado alrededor de 50 personas, entre miembros de la asociaci\u00f3n y trabajadores y trabajadoras de la planta. <\/p>\n<p>El encuentro cont\u00f3 con la presencia del atleta adaptado Adnan Almousa Alfermli, deportista internacional reconocido por sus m\u00faltiples Guinness World Records y por su labor de sensibilizaci\u00f3n sobre inclusi\u00f3n y superaci\u00f3n personal. Adnan es un activo divulgador de la accesibilidad y la igualdad y su trayectoria vital, marcada por la resiliencia y la motivaci\u00f3n, constituye un ejemplo para romper l\u00edmites.<\/p>\n<p>Tras su presentaci\u00f3n, Adnan dirigi\u00f3 diversas actividades deportivas adaptadas en las instalaciones de la f\u00e1brica, fomentando la participaci\u00f3n activa, el trabajo en equipo y la convivencia. Las din\u00e1micas, dise\u00f1adas para que todas las personas pudieran disfrutar y colaborar, generaron un ambiente de motivaci\u00f3n y compa\u00f1erismo.<\/p>\n<p>La jornada concluy\u00f3 con una valoraci\u00f3n muy positiva por parte de los participantes, que destacaron la oportunidad de compartir experiencias y aprender a trav\u00e9s del deporte. La convivencia entre personas con distintas capacidades puso de manifiesto el valor del esfuerzo colectivo y la capacidad para afrontar retos y descubrir nuevas fortalezas. Tambi\u00e9n supuso una motivaci\u00f3n, al mostrar c\u00f3mo el deporte inclusivo favorece la confianza, la autonom\u00eda y la superaci\u00f3n de barreras, reforzando el compromiso para avanzar hacia una sociedad m\u00e1s abierta y diversa.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El encuentro cont\u00f3 con la presencia del atleta adaptado Adnan Almousa Alfermli, deportista internacional reconocido por sus m\u00faltiples Guinness World Records y por su labor de sensibilizaci\u00f3n sobre inclusi\u00f3n y superaci\u00f3n personal. <\/p>\n","protected":false},"author":2,"featured_media":32039,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[237,231,239],"tags":[],"class_list":["post-32036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-diversidad","category-fabrica-de-toral-de-los-vados","category-sostenibilidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La f\u00e1brica de Toral celebra una jornada deportiva inclusiva con Asprona Bierzo y el atleta Adnan Almousa Alfermli | Votorantim Cimentos Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-toral-celebra-una-jornada-deportiva-inclusiva-con-asprona-bierzo-y-el-atleta-adnan-almousa-alfermli\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La f\u00e1brica de Toral celebra una jornada deportiva inclusiva con Asprona Bierzo y el atleta Adnan Almousa Alfermli | Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"El encuentro cont\u00f3 con la presencia del atleta adaptado Adnan Almousa Alfermli, deportista internacional reconocido por sus m\u00faltiples Guinness World Records y por su labor de sensibilizaci\u00f3n sobre inclusi\u00f3n y superaci\u00f3n personal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-toral-celebra-una-jornada-deportiva-inclusiva-con-asprona-bierzo-y-el-atleta-adnan-almousa-alfermli\/\" \/>\n<meta property=\"og:site_name\" content=\"Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-03T07:42:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2026\/07\/260703-Asprona-Bierzo-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Votorantim Cimentos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Votorantim Cimentos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-toral-celebra-una-jornada-deportiva-inclusiva-con-asprona-bierzo-y-el-atleta-adnan-almousa-alfermli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-toral-celebra-una-jornada-deportiva-inclusiva-con-asprona-bierzo-y-el-atleta-adnan-almousa-alfermli\\\/\"},\"author\":{\"name\":\"Votorantim Cimentos\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#\\\/schema\\\/person\\\/4de32fe180e055b1d423bbdfa28b3044\"},\"headline\":\"La f\u00e1brica de Toral celebra una jornada deportiva inclusiva con Asprona Bierzo y el atleta Adnan Almousa Alfermli\",\"datePublished\":\"2026-07-03T07:42:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-toral-celebra-una-jornada-deportiva-inclusiva-con-asprona-bierzo-y-el-atleta-adnan-almousa-alfermli\\\/\"},\"wordCount\":994,\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-toral-celebra-una-jornada-deportiva-inclusiva-con-asprona-bierzo-y-el-atleta-adnan-almousa-alfermli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/260703-Asprona-Bierzo-2-scaled.jpg\",\"articleSection\":[\"Diversidad\",\"F\u00e1brica de Toral de los Vados\",\"Sostenibilidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-toral-celebra-una-jornada-deportiva-inclusiva-con-asprona-bierzo-y-el-atleta-adnan-almousa-alfermli\\\/\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-toral-celebra-una-jornada-deportiva-inclusiva-con-asprona-bierzo-y-el-atleta-adnan-almousa-alfermli\\\/\",\"name\":\"La f\u00e1brica de Toral celebra una jornada deportiva inclusiva con Asprona Bierzo y el atleta Adnan Almousa Alfermli | Votorantim Cimentos Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-toral-celebra-una-jornada-deportiva-inclusiva-con-asprona-bierzo-y-el-atleta-adnan-almousa-alfermli\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-toral-celebra-una-jornada-deportiva-inclusiva-con-asprona-bierzo-y-el-atleta-adnan-almousa-alfermli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/260703-Asprona-Bierzo-2-scaled.jpg\",\"datePublished\":\"2026-07-03T07:42:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#\\\/schema\\\/person\\\/4de32fe180e055b1d423bbdfa28b3044\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-toral-celebra-una-jornada-deportiva-inclusiva-con-asprona-bierzo-y-el-atleta-adnan-almousa-alfermli\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-toral-celebra-una-jornada-deportiva-inclusiva-con-asprona-bierzo-y-el-atleta-adnan-almousa-alfermli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-toral-celebra-una-jornada-deportiva-inclusiva-con-asprona-bierzo-y-el-atleta-adnan-almousa-alfermli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/260703-Asprona-Bierzo-2-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/260703-Asprona-Bierzo-2-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-toral-celebra-una-jornada-deportiva-inclusiva-con-asprona-bierzo-y-el-atleta-adnan-almousa-alfermli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La f\u00e1brica de Toral celebra una jornada deportiva inclusiva con Asprona Bierzo y el atleta Adnan Almousa Alfermli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/\",\"name\":\"Votorantim Cimentos Espa\u00f1a\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#\\\/schema\\\/person\\\/4de32fe180e055b1d423bbdfa28b3044\",\"name\":\"Votorantim Cimentos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6df14fcca736e04ee8aeb4a1c51fd540d783a0ceb50876d491e877a532c0c3e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6df14fcca736e04ee8aeb4a1c51fd540d783a0ceb50876d491e877a532c0c3e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6df14fcca736e04ee8aeb4a1c51fd540d783a0ceb50876d491e877a532c0c3e?s=96&d=mm&r=g\",\"caption\":\"Votorantim Cimentos\"},\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/author\\\/votorantim\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La f\u00e1brica de Toral celebra una jornada deportiva inclusiva con Asprona Bierzo y el atleta Adnan Almousa Alfermli | Votorantim Cimentos Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-toral-celebra-una-jornada-deportiva-inclusiva-con-asprona-bierzo-y-el-atleta-adnan-almousa-alfermli\/","og_locale":"es_ES","og_type":"article","og_title":"La f\u00e1brica de Toral celebra una jornada deportiva inclusiva con Asprona Bierzo y el atleta Adnan Almousa Alfermli | Votorantim Cimentos Espa\u00f1a","og_description":"El encuentro cont\u00f3 con la presencia del atleta adaptado Adnan Almousa Alfermli, deportista internacional reconocido por sus m\u00faltiples Guinness World Records y por su labor de sensibilizaci\u00f3n sobre inclusi\u00f3n y superaci\u00f3n personal.","og_url":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-toral-celebra-una-jornada-deportiva-inclusiva-con-asprona-bierzo-y-el-atleta-adnan-almousa-alfermli\/","og_site_name":"Votorantim Cimentos Espa\u00f1a","article_published_time":"2026-07-03T07:42:44+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2026\/07\/260703-Asprona-Bierzo-2-scaled.jpg","type":"image\/jpeg"}],"author":"Votorantim Cimentos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Votorantim Cimentos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-toral-celebra-una-jornada-deportiva-inclusiva-con-asprona-bierzo-y-el-atleta-adnan-almousa-alfermli\/#article","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-toral-celebra-una-jornada-deportiva-inclusiva-con-asprona-bierzo-y-el-atleta-adnan-almousa-alfermli\/"},"author":{"name":"Votorantim Cimentos","@id":"https:\/\/www.votorantimcimentos.es\/es\/#\/schema\/person\/4de32fe180e055b1d423bbdfa28b3044"},"headline":"La f\u00e1brica de Toral celebra una jornada deportiva inclusiva con Asprona Bierzo y el atleta Adnan Almousa Alfermli","datePublished":"2026-07-03T07:42:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-toral-celebra-una-jornada-deportiva-inclusiva-con-asprona-bierzo-y-el-atleta-adnan-almousa-alfermli\/"},"wordCount":994,"image":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-toral-celebra-una-jornada-deportiva-inclusiva-con-asprona-bierzo-y-el-atleta-adnan-almousa-alfermli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2026\/07\/260703-Asprona-Bierzo-2-scaled.jpg","articleSection":["Diversidad","F\u00e1brica de Toral de los Vados","Sostenibilidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-toral-celebra-una-jornada-deportiva-inclusiva-con-asprona-bierzo-y-el-atleta-adnan-almousa-alfermli\/","url":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-toral-celebra-una-jornada-deportiva-inclusiva-con-asprona-bierzo-y-el-atleta-adnan-almousa-alfermli\/","name":"La f\u00e1brica de Toral celebra una jornada deportiva inclusiva con Asprona Bierzo y el atleta Adnan Almousa Alfermli | Votorantim Cimentos Espa\u00f1a","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-toral-celebra-una-jornada-deportiva-inclusiva-con-asprona-bierzo-y-el-atleta-adnan-almousa-alfermli\/#primaryimage"},"image":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-toral-celebra-una-jornada-deportiva-inclusiva-con-asprona-bierzo-y-el-atleta-adnan-almousa-alfermli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2026\/07\/260703-Asprona-Bierzo-2-scaled.jpg","datePublished":"2026-07-03T07:42:44+00:00","author":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/#\/schema\/person\/4de32fe180e055b1d423bbdfa28b3044"},"breadcrumb":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-toral-celebra-una-jornada-deportiva-inclusiva-con-asprona-bierzo-y-el-atleta-adnan-almousa-alfermli\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-toral-celebra-una-jornada-deportiva-inclusiva-con-asprona-bierzo-y-el-atleta-adnan-almousa-alfermli\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-toral-celebra-una-jornada-deportiva-inclusiva-con-asprona-bierzo-y-el-atleta-adnan-almousa-alfermli\/#primaryimage","url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2026\/07\/260703-Asprona-Bierzo-2-scaled.jpg","contentUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2026\/07\/260703-Asprona-Bierzo-2-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-toral-celebra-una-jornada-deportiva-inclusiva-con-asprona-bierzo-y-el-atleta-adnan-almousa-alfermli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.votorantimcimentos.es\/es\/"},{"@type":"ListItem","position":2,"name":"La f\u00e1brica de Toral celebra una jornada deportiva inclusiva con Asprona Bierzo y el atleta Adnan Almousa Alfermli"}]},{"@type":"WebSite","@id":"https:\/\/www.votorantimcimentos.es\/es\/#website","url":"https:\/\/www.votorantimcimentos.es\/es\/","name":"Votorantim Cimentos Espa\u00f1a","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.votorantimcimentos.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.votorantimcimentos.es\/es\/#\/schema\/person\/4de32fe180e055b1d423bbdfa28b3044","name":"Votorantim Cimentos","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a6df14fcca736e04ee8aeb4a1c51fd540d783a0ceb50876d491e877a532c0c3e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a6df14fcca736e04ee8aeb4a1c51fd540d783a0ceb50876d491e877a532c0c3e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a6df14fcca736e04ee8aeb4a1c51fd540d783a0ceb50876d491e877a532c0c3e?s=96&d=mm&r=g","caption":"Votorantim Cimentos"},"url":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/author\/votorantim\/"}]}},"_links":{"self":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts\/32036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/comments?post=32036"}],"version-history":[{"count":2,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts\/32036\/revisions"}],"predecessor-version":[{"id":32042,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts\/32036\/revisions\/32042"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/media\/32039"}],"wp:attachment":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/media?parent=32036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/categories?post=32036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/tags?post=32036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}