{"id":31346,"date":"2025-09-29T07:51:28","date_gmt":"2025-09-29T05:51:28","guid":{"rendered":"https:\/\/www.votorantimcimentos.es\/?p=31346"},"modified":"2025-09-29T07:51:28","modified_gmt":"2025-09-29T05:51:28","slug":"mas-de-500-personas-visitan-la-fabrica-de-toral-en-la-jornada-de-puertas-abiertas-organizada-por-cementos-cosmos","status":"publish","type":"post","link":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/mas-de-500-personas-visitan-la-fabrica-de-toral-en-la-jornada-de-puertas-abiertas-organizada-por-cementos-cosmos\/","title":{"rendered":"M\u00e1s de 500 personas visitan la f\u00e1brica de Toral en la Jornada de Puertas Abiertas organizada por Cementos Cosmos"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p><b><i>Toral de los Vados<\/i>, 27 de septiembre de 2025.-<\/b> M\u00e1s de medio millar de vecinos y vecinas del entorno de Toral de los Vados han disfrutado esta ma\u00f1ana de la Jornada de Puertas Abiertas que ha organizado Cementos Cosmos. Con esta iniciativa, los visitantes han podido familiarizarse con una industria que lleva m\u00e1s de cien a\u00f1os generando riqueza y empleo en la zona y cuyos productos forman parte de las obras m\u00e1s destacadas de la comarca, tanto de edificaci\u00f3n como infraestructuras.<\/p>\n<p>Los asistentes han sido recibidos por el director de la f\u00e1brica, Jaime Santoalla, as\u00ed como por otros miembros del equipo directivo y t\u00e9cnico de la empresa. Posteriormente han recorrido las instalaciones acompa\u00f1ados por miembros del equipo t\u00e9cnico, quienes les han explicado las diferentes fases de la producci\u00f3n del cemento, as\u00ed como las \u00faltimas inversiones realizadas para la modernizaci\u00f3n de las instalaciones, mejora de la eficiencia energ\u00e9tica y protecci\u00f3n del medio ambiente y el entorno con el objetivo de ser cada d\u00eda m\u00e1s sostenibles y alcanzar el reto de producir hormig\u00f3n neutro en carbono en 2050<\/p>\n<p>Jaime Santoalla, director de la cementera, ha comentado al respecto: \u201cPara nosotros, una vez m\u00e1s, ha sido muy satisfactorio poder compartir con nuestros vecinos y vecinas el funcionamiento de una industria que forma parte de la historia del Bierzo desde hace m\u00e1s de un siglo. Una jornada que reafirma el v\u00ednculo existente entre la f\u00e1brica y el entorno y que nos permite mostrar el proceso de fabricaci\u00f3n de uno de los materiales de construcci\u00f3n m\u00e1s utilizados\u201d.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Con esta iniciativa, los visitantes han podido familiarizarse con una industria que lleva m\u00e1s de cien a\u00f1os generando riqueza y empleo en la zona y cuyos productos forman parte de las obras m\u00e1s destacadas de la comarca, tanto de edificaci\u00f3n como infraestructuras.<\/p>\n","protected":false},"author":2,"featured_media":31349,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[231],"tags":[],"class_list":["post-31346","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fabrica-de-toral-de-los-vados"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e1s de 500 personas visitan la f\u00e1brica de Toral en la Jornada de Puertas Abiertas organizada por Cementos Cosmos | Votorantim Cimentos Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.votorantimcimentos.es\/es\/noticias\/mas-de-500-personas-visitan-la-fabrica-de-toral-en-la-jornada-de-puertas-abiertas-organizada-por-cementos-cosmos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1s de 500 personas visitan la f\u00e1brica de Toral en la Jornada de Puertas Abiertas organizada por Cementos Cosmos | Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"Con esta iniciativa, los visitantes han podido familiarizarse con una industria que lleva m\u00e1s de cien a\u00f1os generando riqueza y empleo en la zona y cuyos productos forman parte de las obras m\u00e1s destacadas de la comarca, tanto de edificaci\u00f3n como infraestructuras.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.votorantimcimentos.es\/es\/noticias\/mas-de-500-personas-visitan-la-fabrica-de-toral-en-la-jornada-de-puertas-abiertas-organizada-por-cementos-cosmos\/\" \/>\n<meta property=\"og:site_name\" content=\"Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-29T05:51:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2025\/09\/Puertas-Abiertas-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2016\" \/>\n\t<meta property=\"og:image:height\" content=\"1512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Votorantim Cimentos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Votorantim Cimentos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/mas-de-500-personas-visitan-la-fabrica-de-toral-en-la-jornada-de-puertas-abiertas-organizada-por-cementos-cosmos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/mas-de-500-personas-visitan-la-fabrica-de-toral-en-la-jornada-de-puertas-abiertas-organizada-por-cementos-cosmos\\\/\"},\"author\":{\"name\":\"Votorantim Cimentos\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#\\\/schema\\\/person\\\/4de32fe180e055b1d423bbdfa28b3044\"},\"headline\":\"M\u00e1s de 500 personas visitan la f\u00e1brica de Toral en la Jornada de Puertas Abiertas organizada por Cementos Cosmos\",\"datePublished\":\"2025-09-29T05:51:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/mas-de-500-personas-visitan-la-fabrica-de-toral-en-la-jornada-de-puertas-abiertas-organizada-por-cementos-cosmos\\\/\"},\"wordCount\":968,\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/mas-de-500-personas-visitan-la-fabrica-de-toral-en-la-jornada-de-puertas-abiertas-organizada-por-cementos-cosmos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Puertas-Abiertas-2.jpg\",\"articleSection\":[\"F\u00e1brica de Toral de los Vados\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/mas-de-500-personas-visitan-la-fabrica-de-toral-en-la-jornada-de-puertas-abiertas-organizada-por-cementos-cosmos\\\/\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/mas-de-500-personas-visitan-la-fabrica-de-toral-en-la-jornada-de-puertas-abiertas-organizada-por-cementos-cosmos\\\/\",\"name\":\"M\u00e1s de 500 personas visitan la f\u00e1brica de Toral en la Jornada de Puertas Abiertas organizada por Cementos Cosmos | Votorantim Cimentos Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/mas-de-500-personas-visitan-la-fabrica-de-toral-en-la-jornada-de-puertas-abiertas-organizada-por-cementos-cosmos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/mas-de-500-personas-visitan-la-fabrica-de-toral-en-la-jornada-de-puertas-abiertas-organizada-por-cementos-cosmos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Puertas-Abiertas-2.jpg\",\"datePublished\":\"2025-09-29T05:51:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#\\\/schema\\\/person\\\/4de32fe180e055b1d423bbdfa28b3044\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/mas-de-500-personas-visitan-la-fabrica-de-toral-en-la-jornada-de-puertas-abiertas-organizada-por-cementos-cosmos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/mas-de-500-personas-visitan-la-fabrica-de-toral-en-la-jornada-de-puertas-abiertas-organizada-por-cementos-cosmos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/mas-de-500-personas-visitan-la-fabrica-de-toral-en-la-jornada-de-puertas-abiertas-organizada-por-cementos-cosmos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Puertas-Abiertas-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Puertas-Abiertas-2.jpg\",\"width\":2016,\"height\":1512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/mas-de-500-personas-visitan-la-fabrica-de-toral-en-la-jornada-de-puertas-abiertas-organizada-por-cementos-cosmos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e1s de 500 personas visitan la f\u00e1brica de Toral en la Jornada de Puertas Abiertas organizada por Cementos Cosmos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/\",\"name\":\"Votorantim Cimentos Espa\u00f1a\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#\\\/schema\\\/person\\\/4de32fe180e055b1d423bbdfa28b3044\",\"name\":\"Votorantim Cimentos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6df14fcca736e04ee8aeb4a1c51fd540d783a0ceb50876d491e877a532c0c3e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6df14fcca736e04ee8aeb4a1c51fd540d783a0ceb50876d491e877a532c0c3e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6df14fcca736e04ee8aeb4a1c51fd540d783a0ceb50876d491e877a532c0c3e?s=96&d=mm&r=g\",\"caption\":\"Votorantim Cimentos\"},\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/author\\\/votorantim\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1s de 500 personas visitan la f\u00e1brica de Toral en la Jornada de Puertas Abiertas organizada por Cementos Cosmos | Votorantim Cimentos Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/mas-de-500-personas-visitan-la-fabrica-de-toral-en-la-jornada-de-puertas-abiertas-organizada-por-cementos-cosmos\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e1s de 500 personas visitan la f\u00e1brica de Toral en la Jornada de Puertas Abiertas organizada por Cementos Cosmos | Votorantim Cimentos Espa\u00f1a","og_description":"Con esta iniciativa, los visitantes han podido familiarizarse con una industria que lleva m\u00e1s de cien a\u00f1os generando riqueza y empleo en la zona y cuyos productos forman parte de las obras m\u00e1s destacadas de la comarca, tanto de edificaci\u00f3n como infraestructuras.","og_url":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/mas-de-500-personas-visitan-la-fabrica-de-toral-en-la-jornada-de-puertas-abiertas-organizada-por-cementos-cosmos\/","og_site_name":"Votorantim Cimentos Espa\u00f1a","article_published_time":"2025-09-29T05:51:28+00:00","og_image":[{"width":2016,"height":1512,"url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2025\/09\/Puertas-Abiertas-2.jpg","type":"image\/jpeg"}],"author":"Votorantim Cimentos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Votorantim Cimentos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/mas-de-500-personas-visitan-la-fabrica-de-toral-en-la-jornada-de-puertas-abiertas-organizada-por-cementos-cosmos\/#article","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/mas-de-500-personas-visitan-la-fabrica-de-toral-en-la-jornada-de-puertas-abiertas-organizada-por-cementos-cosmos\/"},"author":{"name":"Votorantim Cimentos","@id":"https:\/\/www.votorantimcimentos.es\/es\/#\/schema\/person\/4de32fe180e055b1d423bbdfa28b3044"},"headline":"M\u00e1s de 500 personas visitan la f\u00e1brica de Toral en la Jornada de Puertas Abiertas organizada por Cementos Cosmos","datePublished":"2025-09-29T05:51:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/mas-de-500-personas-visitan-la-fabrica-de-toral-en-la-jornada-de-puertas-abiertas-organizada-por-cementos-cosmos\/"},"wordCount":968,"image":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/mas-de-500-personas-visitan-la-fabrica-de-toral-en-la-jornada-de-puertas-abiertas-organizada-por-cementos-cosmos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2025\/09\/Puertas-Abiertas-2.jpg","articleSection":["F\u00e1brica de Toral de los Vados"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/mas-de-500-personas-visitan-la-fabrica-de-toral-en-la-jornada-de-puertas-abiertas-organizada-por-cementos-cosmos\/","url":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/mas-de-500-personas-visitan-la-fabrica-de-toral-en-la-jornada-de-puertas-abiertas-organizada-por-cementos-cosmos\/","name":"M\u00e1s de 500 personas visitan la f\u00e1brica de Toral en la Jornada de Puertas Abiertas organizada por Cementos Cosmos | Votorantim Cimentos Espa\u00f1a","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/mas-de-500-personas-visitan-la-fabrica-de-toral-en-la-jornada-de-puertas-abiertas-organizada-por-cementos-cosmos\/#primaryimage"},"image":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/mas-de-500-personas-visitan-la-fabrica-de-toral-en-la-jornada-de-puertas-abiertas-organizada-por-cementos-cosmos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2025\/09\/Puertas-Abiertas-2.jpg","datePublished":"2025-09-29T05:51:28+00:00","author":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/#\/schema\/person\/4de32fe180e055b1d423bbdfa28b3044"},"breadcrumb":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/mas-de-500-personas-visitan-la-fabrica-de-toral-en-la-jornada-de-puertas-abiertas-organizada-por-cementos-cosmos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.votorantimcimentos.es\/es\/noticias\/mas-de-500-personas-visitan-la-fabrica-de-toral-en-la-jornada-de-puertas-abiertas-organizada-por-cementos-cosmos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/mas-de-500-personas-visitan-la-fabrica-de-toral-en-la-jornada-de-puertas-abiertas-organizada-por-cementos-cosmos\/#primaryimage","url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2025\/09\/Puertas-Abiertas-2.jpg","contentUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2025\/09\/Puertas-Abiertas-2.jpg","width":2016,"height":1512},{"@type":"BreadcrumbList","@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/mas-de-500-personas-visitan-la-fabrica-de-toral-en-la-jornada-de-puertas-abiertas-organizada-por-cementos-cosmos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.votorantimcimentos.es\/es\/"},{"@type":"ListItem","position":2,"name":"M\u00e1s de 500 personas visitan la f\u00e1brica de Toral en la Jornada de Puertas Abiertas organizada por Cementos Cosmos"}]},{"@type":"WebSite","@id":"https:\/\/www.votorantimcimentos.es\/es\/#website","url":"https:\/\/www.votorantimcimentos.es\/es\/","name":"Votorantim Cimentos Espa\u00f1a","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.votorantimcimentos.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.votorantimcimentos.es\/es\/#\/schema\/person\/4de32fe180e055b1d423bbdfa28b3044","name":"Votorantim Cimentos","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a6df14fcca736e04ee8aeb4a1c51fd540d783a0ceb50876d491e877a532c0c3e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a6df14fcca736e04ee8aeb4a1c51fd540d783a0ceb50876d491e877a532c0c3e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a6df14fcca736e04ee8aeb4a1c51fd540d783a0ceb50876d491e877a532c0c3e?s=96&d=mm&r=g","caption":"Votorantim Cimentos"},"url":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/author\/votorantim\/"}]}},"_links":{"self":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts\/31346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/comments?post=31346"}],"version-history":[{"count":2,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts\/31346\/revisions"}],"predecessor-version":[{"id":31352,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts\/31346\/revisions\/31352"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/media\/31349"}],"wp:attachment":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/media?parent=31346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/categories?post=31346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/tags?post=31346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}