{"id":25344,"date":"2023-12-13T09:48:26","date_gmt":"2023-12-13T08:48:26","guid":{"rendered":"https:\/\/www.votorantimcimentos.es\/?p=25344"},"modified":"2024-04-18T11:22:52","modified_gmt":"2024-04-18T09:22:52","slug":"los-trabajadores-de-votorantim-cimentos-donan-3-000-euros-a-los-bancos-de-alimentos-de-toral-y-sil-ponferrada-2","status":"publish","type":"post","link":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/los-trabajadores-de-votorantim-cimentos-donan-3-000-euros-a-los-bancos-de-alimentos-de-toral-y-sil-ponferrada-2\/","title":{"rendered":"Los trabajadores de Votorantim Cimentos donan 3.000 euros a los bancos de alimentos de Toral y Sil-Ponferrada"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p><b><i>Toral de los Vados<\/i>, 13 de diciembre de 2023.-<\/b> Un a\u00f1o m\u00e1s, Votorantim Cimentos y los trabajadores de la f\u00e1brica de Toral de los Vados, fieles a su compromiso con el entorno, han realizado una donaci\u00f3n de 3.000 euros a los bancos de alimentos de Toral y Sil-Ponferrada. Estos fondos se destinar\u00e1n a la compra de alimentos y productos de primera necesidad para su distribuci\u00f3n entre ONGs y otras instituciones de ayuda social de la zona.<\/p>\n<p>El acto de entrega de las donaciones se ha celebrado en el Ayuntamiento de Toral de los Vados y la sede de Banco de Alimentos de Sil-Ponferrada y ha contado con la presencia de representantes de las dos organizaciones, de los trabajadores de la cementera de Toral y del director de la f\u00e1brica, Jaime Santoalla.<\/p>\n<p>El presidente del Comit\u00e9 de Empresa de la planta de Toral asegur\u00f3 que, \u00ablos empleados acudimos a nuestra cita anual desde 2013 para ayudar a las familias m\u00e1s desfavorecidas de nuestro entorno y aportarles, en la medida de lo posible, nuestro apoyo y colaboraci\u00f3n para superar los momentos dif\u00edciles que est\u00e1n pasando\u00bb.<\/p>\n<p>Por su parte, el director de la f\u00e1brica ha querido agradecer la importante labor de instituciones como el Banco de Alimentos, que distribuyen ayuda alimentaria a personas en pobreza o riesgo de exclusi\u00f3n social. Santoalla ha recordado que \u00aben Votorantim Cimentos nos consideramos parte de las comunidades donde operamos y sus necesidades las sentimos nuestras, de ah\u00ed nuestra participaci\u00f3n en iniciativas como esta para ayudar a las familias con menos recursos\u00bb.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Estos fondos se destinar\u00e1n a la compra de alimentos y productos de primera necesidad para su distribuci\u00f3n entre ONGs y otras instituciones de ayuda social de la zona.<\/p>\n","protected":false},"author":2,"featured_media":25346,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[231,239],"tags":[],"class_list":["post-25344","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fabrica-de-toral-de-los-vados","category-sostenibilidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los trabajadores de Votorantim Cimentos donan 3.000 euros a los bancos de alimentos de Toral y Sil-Ponferrada en 2023 | Votorantim Cimentos Espa\u00f1a<\/title>\n<meta name=\"description\" content=\"Estos fondos se destinar\u00e1n a la compra de alimentos y productos de primera necesidad para su distribuci\u00f3n entre ONGs y otras instituciones de ayuda social de la zona.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.votorantimcimentos.es\/es\/noticias\/los-trabajadores-de-votorantim-cimentos-donan-3-000-euros-a-los-bancos-de-alimentos-de-toral-y-sil-ponferrada-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los trabajadores de Votorantim Cimentos donan 3.000 euros a los bancos de alimentos de Toral y Sil-Ponferrada en 2023 | Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"Estos fondos se destinar\u00e1n a la compra de alimentos y productos de primera necesidad para su distribuci\u00f3n entre ONGs y otras instituciones de ayuda social de la zona.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.votorantimcimentos.es\/es\/noticias\/los-trabajadores-de-votorantim-cimentos-donan-3-000-euros-a-los-bancos-de-alimentos-de-toral-y-sil-ponferrada-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-13T08:48:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-18T09:22:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/BA-Sil-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Votorantim Cimentos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Votorantim Cimentos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/los-trabajadores-de-votorantim-cimentos-donan-3-000-euros-a-los-bancos-de-alimentos-de-toral-y-sil-ponferrada-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/los-trabajadores-de-votorantim-cimentos-donan-3-000-euros-a-los-bancos-de-alimentos-de-toral-y-sil-ponferrada-2\\\/\"},\"author\":{\"name\":\"Votorantim Cimentos\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#\\\/schema\\\/person\\\/4de32fe180e055b1d423bbdfa28b3044\"},\"headline\":\"Los trabajadores de Votorantim Cimentos donan 3.000 euros a los bancos de alimentos de Toral y Sil-Ponferrada\",\"datePublished\":\"2023-12-13T08:48:26+00:00\",\"dateModified\":\"2024-04-18T09:22:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/los-trabajadores-de-votorantim-cimentos-donan-3-000-euros-a-los-bancos-de-alimentos-de-toral-y-sil-ponferrada-2\\\/\"},\"wordCount\":885,\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/los-trabajadores-de-votorantim-cimentos-donan-3-000-euros-a-los-bancos-de-alimentos-de-toral-y-sil-ponferrada-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/BA-Sil-scaled.jpeg\",\"articleSection\":[\"F\u00e1brica de Toral de los Vados\",\"Sostenibilidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/los-trabajadores-de-votorantim-cimentos-donan-3-000-euros-a-los-bancos-de-alimentos-de-toral-y-sil-ponferrada-2\\\/\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/los-trabajadores-de-votorantim-cimentos-donan-3-000-euros-a-los-bancos-de-alimentos-de-toral-y-sil-ponferrada-2\\\/\",\"name\":\"Los trabajadores de Votorantim Cimentos donan 3.000 euros a los bancos de alimentos de Toral y Sil-Ponferrada en 2023 | Votorantim Cimentos Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/los-trabajadores-de-votorantim-cimentos-donan-3-000-euros-a-los-bancos-de-alimentos-de-toral-y-sil-ponferrada-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/los-trabajadores-de-votorantim-cimentos-donan-3-000-euros-a-los-bancos-de-alimentos-de-toral-y-sil-ponferrada-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/BA-Sil-scaled.jpeg\",\"datePublished\":\"2023-12-13T08:48:26+00:00\",\"dateModified\":\"2024-04-18T09:22:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#\\\/schema\\\/person\\\/4de32fe180e055b1d423bbdfa28b3044\"},\"description\":\"Estos fondos se destinar\u00e1n a la compra de alimentos y productos de primera necesidad para su distribuci\u00f3n entre ONGs y otras instituciones de ayuda social de la zona.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/los-trabajadores-de-votorantim-cimentos-donan-3-000-euros-a-los-bancos-de-alimentos-de-toral-y-sil-ponferrada-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/los-trabajadores-de-votorantim-cimentos-donan-3-000-euros-a-los-bancos-de-alimentos-de-toral-y-sil-ponferrada-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/los-trabajadores-de-votorantim-cimentos-donan-3-000-euros-a-los-bancos-de-alimentos-de-toral-y-sil-ponferrada-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/BA-Sil-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/BA-Sil-scaled.jpeg\",\"width\":2560,\"height\":1920,\"caption\":\"Banco de Alimentos el Sil y Votorantim Cimentos Espa\u00f1a\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/los-trabajadores-de-votorantim-cimentos-donan-3-000-euros-a-los-bancos-de-alimentos-de-toral-y-sil-ponferrada-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los trabajadores de Votorantim Cimentos donan 3.000 euros a los bancos de alimentos de Toral y Sil-Ponferrada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/\",\"name\":\"Votorantim Cimentos Espa\u00f1a\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#\\\/schema\\\/person\\\/4de32fe180e055b1d423bbdfa28b3044\",\"name\":\"Votorantim Cimentos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6df14fcca736e04ee8aeb4a1c51fd540d783a0ceb50876d491e877a532c0c3e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6df14fcca736e04ee8aeb4a1c51fd540d783a0ceb50876d491e877a532c0c3e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6df14fcca736e04ee8aeb4a1c51fd540d783a0ceb50876d491e877a532c0c3e?s=96&d=mm&r=g\",\"caption\":\"Votorantim Cimentos\"},\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/author\\\/votorantim\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los trabajadores de Votorantim Cimentos donan 3.000 euros a los bancos de alimentos de Toral y Sil-Ponferrada en 2023 | Votorantim Cimentos Espa\u00f1a","description":"Estos fondos se destinar\u00e1n a la compra de alimentos y productos de primera necesidad para su distribuci\u00f3n entre ONGs y otras instituciones de ayuda social de la zona.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/los-trabajadores-de-votorantim-cimentos-donan-3-000-euros-a-los-bancos-de-alimentos-de-toral-y-sil-ponferrada-2\/","og_locale":"es_ES","og_type":"article","og_title":"Los trabajadores de Votorantim Cimentos donan 3.000 euros a los bancos de alimentos de Toral y Sil-Ponferrada en 2023 | Votorantim Cimentos Espa\u00f1a","og_description":"Estos fondos se destinar\u00e1n a la compra de alimentos y productos de primera necesidad para su distribuci\u00f3n entre ONGs y otras instituciones de ayuda social de la zona.","og_url":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/los-trabajadores-de-votorantim-cimentos-donan-3-000-euros-a-los-bancos-de-alimentos-de-toral-y-sil-ponferrada-2\/","og_site_name":"Votorantim Cimentos Espa\u00f1a","article_published_time":"2023-12-13T08:48:26+00:00","article_modified_time":"2024-04-18T09:22:52+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/BA-Sil-scaled.jpeg","type":"image\/jpeg"}],"author":"Votorantim Cimentos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Votorantim Cimentos","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/los-trabajadores-de-votorantim-cimentos-donan-3-000-euros-a-los-bancos-de-alimentos-de-toral-y-sil-ponferrada-2\/#article","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/los-trabajadores-de-votorantim-cimentos-donan-3-000-euros-a-los-bancos-de-alimentos-de-toral-y-sil-ponferrada-2\/"},"author":{"name":"Votorantim Cimentos","@id":"https:\/\/www.votorantimcimentos.es\/es\/#\/schema\/person\/4de32fe180e055b1d423bbdfa28b3044"},"headline":"Los trabajadores de Votorantim Cimentos donan 3.000 euros a los bancos de alimentos de Toral y Sil-Ponferrada","datePublished":"2023-12-13T08:48:26+00:00","dateModified":"2024-04-18T09:22:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/los-trabajadores-de-votorantim-cimentos-donan-3-000-euros-a-los-bancos-de-alimentos-de-toral-y-sil-ponferrada-2\/"},"wordCount":885,"image":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/los-trabajadores-de-votorantim-cimentos-donan-3-000-euros-a-los-bancos-de-alimentos-de-toral-y-sil-ponferrada-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/BA-Sil-scaled.jpeg","articleSection":["F\u00e1brica de Toral de los Vados","Sostenibilidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/los-trabajadores-de-votorantim-cimentos-donan-3-000-euros-a-los-bancos-de-alimentos-de-toral-y-sil-ponferrada-2\/","url":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/los-trabajadores-de-votorantim-cimentos-donan-3-000-euros-a-los-bancos-de-alimentos-de-toral-y-sil-ponferrada-2\/","name":"Los trabajadores de Votorantim Cimentos donan 3.000 euros a los bancos de alimentos de Toral y Sil-Ponferrada en 2023 | Votorantim Cimentos Espa\u00f1a","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/los-trabajadores-de-votorantim-cimentos-donan-3-000-euros-a-los-bancos-de-alimentos-de-toral-y-sil-ponferrada-2\/#primaryimage"},"image":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/los-trabajadores-de-votorantim-cimentos-donan-3-000-euros-a-los-bancos-de-alimentos-de-toral-y-sil-ponferrada-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/BA-Sil-scaled.jpeg","datePublished":"2023-12-13T08:48:26+00:00","dateModified":"2024-04-18T09:22:52+00:00","author":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/#\/schema\/person\/4de32fe180e055b1d423bbdfa28b3044"},"description":"Estos fondos se destinar\u00e1n a la compra de alimentos y productos de primera necesidad para su distribuci\u00f3n entre ONGs y otras instituciones de ayuda social de la zona.","breadcrumb":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/los-trabajadores-de-votorantim-cimentos-donan-3-000-euros-a-los-bancos-de-alimentos-de-toral-y-sil-ponferrada-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.votorantimcimentos.es\/es\/noticias\/los-trabajadores-de-votorantim-cimentos-donan-3-000-euros-a-los-bancos-de-alimentos-de-toral-y-sil-ponferrada-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/los-trabajadores-de-votorantim-cimentos-donan-3-000-euros-a-los-bancos-de-alimentos-de-toral-y-sil-ponferrada-2\/#primaryimage","url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/BA-Sil-scaled.jpeg","contentUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/BA-Sil-scaled.jpeg","width":2560,"height":1920,"caption":"Banco de Alimentos el Sil y Votorantim Cimentos Espa\u00f1a"},{"@type":"BreadcrumbList","@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/los-trabajadores-de-votorantim-cimentos-donan-3-000-euros-a-los-bancos-de-alimentos-de-toral-y-sil-ponferrada-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.votorantimcimentos.es\/es\/"},{"@type":"ListItem","position":2,"name":"Los trabajadores de Votorantim Cimentos donan 3.000 euros a los bancos de alimentos de Toral y Sil-Ponferrada"}]},{"@type":"WebSite","@id":"https:\/\/www.votorantimcimentos.es\/es\/#website","url":"https:\/\/www.votorantimcimentos.es\/es\/","name":"Votorantim Cimentos Espa\u00f1a","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.votorantimcimentos.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.votorantimcimentos.es\/es\/#\/schema\/person\/4de32fe180e055b1d423bbdfa28b3044","name":"Votorantim Cimentos","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a6df14fcca736e04ee8aeb4a1c51fd540d783a0ceb50876d491e877a532c0c3e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a6df14fcca736e04ee8aeb4a1c51fd540d783a0ceb50876d491e877a532c0c3e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a6df14fcca736e04ee8aeb4a1c51fd540d783a0ceb50876d491e877a532c0c3e?s=96&d=mm&r=g","caption":"Votorantim Cimentos"},"url":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/author\/votorantim\/"}]}},"_links":{"self":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts\/25344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/comments?post=25344"}],"version-history":[{"count":3,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts\/25344\/revisions"}],"predecessor-version":[{"id":26007,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts\/25344\/revisions\/26007"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/media\/25346"}],"wp:attachment":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/media?parent=25344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/categories?post=25344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/tags?post=25344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}