{"id":25186,"date":"2017-04-25T08:25:08","date_gmt":"2017-04-25T06:25:08","guid":{"rendered":"https:\/\/www.votorantimcimentos.es\/noticias\/estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos\/"},"modified":"2024-04-18T11:29:19","modified_gmt":"2024-04-18T09:29:19","slug":"estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos","status":"publish","type":"post","link":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos\/","title":{"rendered":"Estudiantes del Bierzo celebraron el D\u00eda Internacional de la Tierra plantando \u00e1rboles en la cantera de Cementos Cosmos"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>Toral de los Vados, 25 de abril de 2017.- La cantera de Cementos Cosmos en Corull\u00f3n ha recibido la visita de m\u00e1s de 30 escolares de la zona, que plantaron \u00e1rboles con motivo del D\u00eda Internacional de la Tierra, celebrado el 22 de abril. Los j\u00f3venes, que cursan sus estudios en los colegios Jimena de Mu\u00f1iz, de Corull\u00f3n, y de Toral de los Vados, repoblaron un sector previamente seleccionado de la explotaci\u00f3n, acompa\u00f1ados de sus educadores.<\/p>\n<p>La especie elegida para repoblar el sector de la cantera es, como en a\u00f1os anteriores, el cerezo, que se ha convertido en un importante revulsivo para el Bierzo. Tanto el impulso del turismo en \u00e9poca de floraci\u00f3n de estos \u00e1rboles como la exportaci\u00f3n de su fruto constituyen un motor econ\u00f3mico para toda la comarca.<\/p>\n<p>Cementos Cosmos colabora tradicionalmente en la plantaci\u00f3n de \u00e1rboles, abriendo los terrenos de su cantera a los centros educativos del Bierzo. Esta actividad pretende, por una parte, fomentar la conciencia medioambiental de los escolares de la comarca. Al mismo tiempo, la labor de los ni\u00f1os y ni\u00f1as que participan en estas actuaciones contribuye mejorar del entorno natural de la cantera.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La cantera de Cementos Cosmos en Corull\u00f3n ha recibido la visita de m\u00e1s de 30 escolares de la zona, que plantaron \u00e1rboles con motivo del D\u00eda Internacional de la Tierra, celebrado el 22 de abril.<\/p>\n","protected":false},"author":1,"featured_media":25187,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[231,239],"tags":[],"class_list":["post-25186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fabrica-de-toral-de-los-vados","category-sostenibilidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estudiantes del Bierzo celebraron el D\u00eda Internacional de la Tierra plantando \u00e1rboles en la cantera de Cementos Cosmos | Votorantim Cimentos Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.votorantimcimentos.es\/es\/noticias\/estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estudiantes del Bierzo celebraron el D\u00eda Internacional de la Tierra plantando \u00e1rboles en la cantera de Cementos Cosmos | Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"La cantera de Cementos Cosmos en Corull\u00f3n ha recibido la visita de m\u00e1s de 30 escolares de la zona, que plantaron \u00e1rboles con motivo del D\u00eda Internacional de la Tierra, celebrado el 22 de abril.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.votorantimcimentos.es\/es\/noticias\/estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos\/\" \/>\n<meta property=\"og:site_name\" content=\"Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-25T06:25:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-18T09:29:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/corulln2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"teconsite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"teconsite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos\\\/\"},\"author\":{\"name\":\"teconsite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\"},\"headline\":\"Estudiantes del Bierzo celebraron el D\u00eda Internacional de la Tierra plantando \u00e1rboles en la cantera de Cementos Cosmos\",\"datePublished\":\"2017-04-25T06:25:08+00:00\",\"dateModified\":\"2024-04-18T09:29:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos\\\/\"},\"wordCount\":825,\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/corulln2.jpg\",\"articleSection\":[\"F\u00e1brica de Toral de los Vados\",\"Sostenibilidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos\\\/\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos\\\/\",\"name\":\"Estudiantes del Bierzo celebraron el D\u00eda Internacional de la Tierra plantando \u00e1rboles en la cantera de Cementos Cosmos | Votorantim Cimentos Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/corulln2.jpg\",\"datePublished\":\"2017-04-25T06:25:08+00:00\",\"dateModified\":\"2024-04-18T09:29:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/corulln2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/corulln2.jpg\",\"width\":1000,\"height\":750,\"caption\":\"Plantaci\u00f3n de \u00e1rboles en Corull\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estudiantes del Bierzo celebraron el D\u00eda Internacional de la Tierra plantando \u00e1rboles en la cantera de Cementos Cosmos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/\",\"name\":\"Votorantim Cimentos Espa\u00f1a\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\",\"name\":\"teconsite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"caption\":\"teconsite\"},\"sameAs\":[\"https:\\\/\\\/www.votorantimcimentos.es\"],\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/author\\\/teconsite\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estudiantes del Bierzo celebraron el D\u00eda Internacional de la Tierra plantando \u00e1rboles en la cantera de Cementos Cosmos | Votorantim Cimentos Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos\/","og_locale":"es_ES","og_type":"article","og_title":"Estudiantes del Bierzo celebraron el D\u00eda Internacional de la Tierra plantando \u00e1rboles en la cantera de Cementos Cosmos | Votorantim Cimentos Espa\u00f1a","og_description":"La cantera de Cementos Cosmos en Corull\u00f3n ha recibido la visita de m\u00e1s de 30 escolares de la zona, que plantaron \u00e1rboles con motivo del D\u00eda Internacional de la Tierra, celebrado el 22 de abril.","og_url":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos\/","og_site_name":"Votorantim Cimentos Espa\u00f1a","article_published_time":"2017-04-25T06:25:08+00:00","article_modified_time":"2024-04-18T09:29:19+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/corulln2.jpg","type":"image\/jpeg"}],"author":"teconsite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"teconsite","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos\/#article","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos\/"},"author":{"name":"teconsite","@id":"https:\/\/www.votorantimcimentos.es\/es\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d"},"headline":"Estudiantes del Bierzo celebraron el D\u00eda Internacional de la Tierra plantando \u00e1rboles en la cantera de Cementos Cosmos","datePublished":"2017-04-25T06:25:08+00:00","dateModified":"2024-04-18T09:29:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos\/"},"wordCount":825,"image":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/corulln2.jpg","articleSection":["F\u00e1brica de Toral de los Vados","Sostenibilidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos\/","url":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos\/","name":"Estudiantes del Bierzo celebraron el D\u00eda Internacional de la Tierra plantando \u00e1rboles en la cantera de Cementos Cosmos | Votorantim Cimentos Espa\u00f1a","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos\/#primaryimage"},"image":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/corulln2.jpg","datePublished":"2017-04-25T06:25:08+00:00","dateModified":"2024-04-18T09:29:19+00:00","author":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d"},"breadcrumb":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.votorantimcimentos.es\/es\/noticias\/estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos\/#primaryimage","url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/corulln2.jpg","contentUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/corulln2.jpg","width":1000,"height":750,"caption":"Plantaci\u00f3n de \u00e1rboles en Corull\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/estudiantes-del-bierzo-celebraron-el-dia-internacional-de-la-tierra-plantando-arboles-en-la-cantera-de-cementos-cosmos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.votorantimcimentos.es\/es\/"},{"@type":"ListItem","position":2,"name":"Estudiantes del Bierzo celebraron el D\u00eda Internacional de la Tierra plantando \u00e1rboles en la cantera de Cementos Cosmos"}]},{"@type":"WebSite","@id":"https:\/\/www.votorantimcimentos.es\/es\/#website","url":"https:\/\/www.votorantimcimentos.es\/es\/","name":"Votorantim Cimentos Espa\u00f1a","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.votorantimcimentos.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.votorantimcimentos.es\/es\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d","name":"teconsite","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","caption":"teconsite"},"sameAs":["https:\/\/www.votorantimcimentos.es"],"url":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/author\/teconsite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts\/25186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/comments?post=25186"}],"version-history":[{"count":1,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts\/25186\/revisions"}],"predecessor-version":[{"id":25189,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts\/25186\/revisions\/25189"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/media\/25187"}],"wp:attachment":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/media?parent=25186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/categories?post=25186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/tags?post=25186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}