{"id":25155,"date":"2017-08-29T08:25:08","date_gmt":"2017-08-29T06:25:08","guid":{"rendered":"https:\/\/www.votorantimcimentos.es\/noticias\/la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes\/"},"modified":"2024-04-18T11:29:15","modified_gmt":"2024-04-18T09:29:15","slug":"la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes","status":"publish","type":"post","link":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes\/","title":{"rendered":"La Junta rectifica el error de la autorizaci\u00f3n a Cosmos para el uso de cenizas volantes"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>Toral de los Vados, 29 de agosto de 2017.- El BOCyL ha publicado hoy la correcci\u00f3n de la errata cometida por la Consejer\u00eda de Medio Ambiente en la autorizaci\u00f3n que otorg\u00f3 a Cosmos en junio. Dicho tr\u00e1mite permite que la cementera pueda seguir utilizando cenizas volantes como aditivo para producir cemento, a\u00f1adi\u00e9ndolo en la parte final del proceso de fabricaci\u00f3n.<\/p>\n<p>La Consejer\u00eda aclara que en la tabla de \u00abOperaci\u00f3n de tratamiento y relaci\u00f3n de residuos autorizados\u00bb donde dice \u00abcenizas volantes de carb\u00f3n de centrales t\u00e9rmicas para fabricaci\u00f3n de crudo\u00bb, debe decir \u00abcenizas volantes de carb\u00f3n de centrales t\u00e9rmicas para adici\u00f3n en la molienda de cemento\u00bb. <\/p>\n<p>Hasta el momento, las cenizas se recib\u00edan en Cosmos como materia prima, ya que las centrales t\u00e9rmicas las exped\u00edan como subproducto. Sin embargo, ahora, el proveedor, Endesa, ha pasado a considerarlas residuo no peligroso y este es el cambio que se ha recogido en la autorizaci\u00f3n ambiental.<\/p>\n<p>Cementos Cosmos lleva a\u00f1os reciclando las cenizas volantes, incorpor\u00e1ndolas al cemento en la fase de molienda de cl\u00ednker. Los aditivos son necesarios para conferir al cemento determinadas caracter\u00edsticas que los hacen id\u00f3neos para diferentes utilidades. Si este material no se generara en las centrales t\u00e9rmicas, habr\u00eda que buscar uno con propiedades equivalentes en la naturaleza con un impacto ambiental considerablemente mayor. Adem\u00e1s, el reciclado de este material de las t\u00e9rmicas evita que estas acaben en vertederos.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El BOCyL ha publicado hoy la correcci\u00f3n de la errata cometida por la Consejer\u00eda de Medio Ambiente en la autorizaci\u00f3n que otorg\u00f3 a Cosmos en junio. Dicho tr\u00e1mite permite a la cementera seguir utilizando cenizas volantes como aditivo para producir cemento.<\/p>\n","protected":false},"author":1,"featured_media":25156,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[231,239],"tags":[],"class_list":["post-25155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fabrica-de-toral-de-los-vados","category-sostenibilidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Junta rectifica el error de la autorizaci\u00f3n a Cosmos para el uso de cenizas volantes | Votorantim Cimentos Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Junta rectifica el error de la autorizaci\u00f3n a Cosmos para el uso de cenizas volantes | Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"El BOCyL ha publicado hoy la correcci\u00f3n de la errata cometida por la Consejer\u00eda de Medio Ambiente en la autorizaci\u00f3n que otorg\u00f3 a Cosmos en junio. Dicho tr\u00e1mite permite a la cementera seguir utilizando cenizas volantes como aditivo para producir cemento.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes\/\" \/>\n<meta property=\"og:site_name\" content=\"Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-29T06:25:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-18T09:29:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/toral-detalle.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"665\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"teconsite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"teconsite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes\\\/\"},\"author\":{\"name\":\"teconsite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\"},\"headline\":\"La Junta rectifica el error de la autorizaci\u00f3n a Cosmos para el uso de cenizas volantes\",\"datePublished\":\"2017-08-29T06:25:08+00:00\",\"dateModified\":\"2024-04-18T09:29:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes\\\/\"},\"wordCount\":877,\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/toral-detalle.jpg\",\"articleSection\":[\"F\u00e1brica de Toral de los Vados\",\"Sostenibilidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes\\\/\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes\\\/\",\"name\":\"La Junta rectifica el error de la autorizaci\u00f3n a Cosmos para el uso de cenizas volantes | Votorantim Cimentos Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/toral-detalle.jpg\",\"datePublished\":\"2017-08-29T06:25:08+00:00\",\"dateModified\":\"2024-04-18T09:29:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/toral-detalle.jpg\",\"contentUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/toral-detalle.jpg\",\"width\":1000,\"height\":665,\"caption\":\"F\u00e1brica de Toral, Votorantim Cimentos Espa\u00f1a\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Junta rectifica el error de la autorizaci\u00f3n a Cosmos para el uso de cenizas volantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/\",\"name\":\"Votorantim Cimentos Espa\u00f1a\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\",\"name\":\"teconsite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"caption\":\"teconsite\"},\"sameAs\":[\"https:\\\/\\\/www.votorantimcimentos.es\"],\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/author\\\/teconsite\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Junta rectifica el error de la autorizaci\u00f3n a Cosmos para el uso de cenizas volantes | Votorantim Cimentos Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes\/","og_locale":"es_ES","og_type":"article","og_title":"La Junta rectifica el error de la autorizaci\u00f3n a Cosmos para el uso de cenizas volantes | Votorantim Cimentos Espa\u00f1a","og_description":"El BOCyL ha publicado hoy la correcci\u00f3n de la errata cometida por la Consejer\u00eda de Medio Ambiente en la autorizaci\u00f3n que otorg\u00f3 a Cosmos en junio. Dicho tr\u00e1mite permite a la cementera seguir utilizando cenizas volantes como aditivo para producir cemento.","og_url":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes\/","og_site_name":"Votorantim Cimentos Espa\u00f1a","article_published_time":"2017-08-29T06:25:08+00:00","article_modified_time":"2024-04-18T09:29:15+00:00","og_image":[{"width":1000,"height":665,"url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/toral-detalle.jpg","type":"image\/jpeg"}],"author":"teconsite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"teconsite","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes\/#article","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes\/"},"author":{"name":"teconsite","@id":"https:\/\/www.votorantimcimentos.es\/es\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d"},"headline":"La Junta rectifica el error de la autorizaci\u00f3n a Cosmos para el uso de cenizas volantes","datePublished":"2017-08-29T06:25:08+00:00","dateModified":"2024-04-18T09:29:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes\/"},"wordCount":877,"image":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/toral-detalle.jpg","articleSection":["F\u00e1brica de Toral de los Vados","Sostenibilidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes\/","url":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes\/","name":"La Junta rectifica el error de la autorizaci\u00f3n a Cosmos para el uso de cenizas volantes | Votorantim Cimentos Espa\u00f1a","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes\/#primaryimage"},"image":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/toral-detalle.jpg","datePublished":"2017-08-29T06:25:08+00:00","dateModified":"2024-04-18T09:29:15+00:00","author":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d"},"breadcrumb":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes\/#primaryimage","url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/toral-detalle.jpg","contentUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/toral-detalle.jpg","width":1000,"height":665,"caption":"F\u00e1brica de Toral, Votorantim Cimentos Espa\u00f1a"},{"@type":"BreadcrumbList","@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-junta-rectifica-el-error-de-la-autorizacion-a-cosmos-para-el-uso-de-cenizas-volantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.votorantimcimentos.es\/es\/"},{"@type":"ListItem","position":2,"name":"La Junta rectifica el error de la autorizaci\u00f3n a Cosmos para el uso de cenizas volantes"}]},{"@type":"WebSite","@id":"https:\/\/www.votorantimcimentos.es\/es\/#website","url":"https:\/\/www.votorantimcimentos.es\/es\/","name":"Votorantim Cimentos Espa\u00f1a","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.votorantimcimentos.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.votorantimcimentos.es\/es\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d","name":"teconsite","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","caption":"teconsite"},"sameAs":["https:\/\/www.votorantimcimentos.es"],"url":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/author\/teconsite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts\/25155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/comments?post=25155"}],"version-history":[{"count":1,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts\/25155\/revisions"}],"predecessor-version":[{"id":25160,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts\/25155\/revisions\/25160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/media\/25156"}],"wp:attachment":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/media?parent=25155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/categories?post=25155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/tags?post=25155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}