{"id":25107,"date":"2018-01-03T08:25:08","date_gmt":"2018-01-03T07:25:08","guid":{"rendered":"https:\/\/www.votorantimcimentos.es\/noticias\/cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva\/"},"modified":"2024-04-18T11:28:51","modified_gmt":"2024-04-18T09:28:51","slug":"cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva","status":"publish","type":"post","link":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva\/","title":{"rendered":"Cementos Cosmos y sus empleados re\u00fanen dinero y alimentos para el banco de alimentos de Huelva"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>Niebla, 3 de enero de 2018.- Los trabajadores y el Comit\u00e9 de Empresa de la f\u00e1brica de Cementos Cosmos en Niebla han reunido unos 700 kilos de alimentos para el Banco de Alimentos de Huelva. Por su parte, Cementos Cosmos se ha sumado a la iniciativa de la plantilla con la donaci\u00f3n de 1.400 euros, a raz\u00f3n de dos euros por kilo de alimento entregado por sus empleados. La aportaci\u00f3n econ\u00f3mica se ha destinado a comprar productos imperecederos como aceite, leche y alimentos infantiles, que despu\u00e9s ser\u00e1n distribuidos entre ONGs y otras instituciones de ayuda social que trabajan en la zona. <\/p>\n<p>La entrega de la ayuda se llev\u00f3 a cabo en las instalaciones de la cementera. Es el segundo a\u00f1o que los trabajadores llevan a cabo esta iniciativa coincidiendo con las fiestas navide\u00f1as. Adem\u00e1s, la plantilla se implica en otras causas altruistas, como la campa\u00f1a de donaci\u00f3n de sangre que se realiz\u00f3 el pasado mes de noviembre en colaboraci\u00f3n con el Centro de Transfusi\u00f3n, Tejidos y C\u00e9lulas de Huelva.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Los trabajadores y el Comit\u00e9 de Empresa de la f\u00e1brica de Cementos Cosmos en Niebla han reunido unos 700 kilos de alimentos para el Banco de Alimentos de Huelva.<\/p>\n","protected":false},"author":1,"featured_media":25108,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[227,239],"tags":[],"class_list":["post-25107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fabrica-de-niebla","category-sostenibilidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cementos Cosmos y sus empleados re\u00fanen dinero y alimentos para el banco de alimentos de Huelva | Votorantim Cimentos Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.votorantimcimentos.es\/es\/noticias\/cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cementos Cosmos y sus empleados re\u00fanen dinero y alimentos para el banco de alimentos de Huelva | Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"Los trabajadores y el Comit\u00e9 de Empresa de la f\u00e1brica de Cementos Cosmos en Niebla han reunido unos 700 kilos de alimentos para el Banco de Alimentos de Huelva.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.votorantimcimentos.es\/es\/noticias\/cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva\/\" \/>\n<meta property=\"og:site_name\" content=\"Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-03T07:25:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-18T09:28:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/20180103-banco-de-alimentos-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1439\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"teconsite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"teconsite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva\\\/\"},\"author\":{\"name\":\"teconsite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\"},\"headline\":\"Cementos Cosmos y sus empleados re\u00fanen dinero y alimentos para el banco de alimentos de Huelva\",\"datePublished\":\"2018-01-03T07:25:08+00:00\",\"dateModified\":\"2024-04-18T09:28:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva\\\/\"},\"wordCount\":802,\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/20180103-banco-de-alimentos-scaled.jpg\",\"articleSection\":[\"F\u00e1brica de Niebla\",\"Sostenibilidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva\\\/\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva\\\/\",\"name\":\"Cementos Cosmos y sus empleados re\u00fanen dinero y alimentos para el banco de alimentos de Huelva | Votorantim Cimentos Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/20180103-banco-de-alimentos-scaled.jpg\",\"datePublished\":\"2018-01-03T07:25:08+00:00\",\"dateModified\":\"2024-04-18T09:28:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/20180103-banco-de-alimentos-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/20180103-banco-de-alimentos-scaled.jpg\",\"width\":2560,\"height\":1439,\"caption\":\"Donaci\u00f3n al Banco de Alimentos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cementos Cosmos y sus empleados re\u00fanen dinero y alimentos para el banco de alimentos de Huelva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/\",\"name\":\"Votorantim Cimentos Espa\u00f1a\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\",\"name\":\"teconsite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"caption\":\"teconsite\"},\"sameAs\":[\"https:\\\/\\\/www.votorantimcimentos.es\"],\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/author\\\/teconsite\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cementos Cosmos y sus empleados re\u00fanen dinero y alimentos para el banco de alimentos de Huelva | Votorantim Cimentos Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva\/","og_locale":"es_ES","og_type":"article","og_title":"Cementos Cosmos y sus empleados re\u00fanen dinero y alimentos para el banco de alimentos de Huelva | Votorantim Cimentos Espa\u00f1a","og_description":"Los trabajadores y el Comit\u00e9 de Empresa de la f\u00e1brica de Cementos Cosmos en Niebla han reunido unos 700 kilos de alimentos para el Banco de Alimentos de Huelva.","og_url":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva\/","og_site_name":"Votorantim Cimentos Espa\u00f1a","article_published_time":"2018-01-03T07:25:08+00:00","article_modified_time":"2024-04-18T09:28:51+00:00","og_image":[{"width":2560,"height":1439,"url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/20180103-banco-de-alimentos-scaled.jpg","type":"image\/jpeg"}],"author":"teconsite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"teconsite","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva\/#article","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva\/"},"author":{"name":"teconsite","@id":"https:\/\/www.votorantimcimentos.es\/es\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d"},"headline":"Cementos Cosmos y sus empleados re\u00fanen dinero y alimentos para el banco de alimentos de Huelva","datePublished":"2018-01-03T07:25:08+00:00","dateModified":"2024-04-18T09:28:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva\/"},"wordCount":802,"image":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/20180103-banco-de-alimentos-scaled.jpg","articleSection":["F\u00e1brica de Niebla","Sostenibilidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva\/","url":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva\/","name":"Cementos Cosmos y sus empleados re\u00fanen dinero y alimentos para el banco de alimentos de Huelva | Votorantim Cimentos Espa\u00f1a","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva\/#primaryimage"},"image":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/20180103-banco-de-alimentos-scaled.jpg","datePublished":"2018-01-03T07:25:08+00:00","dateModified":"2024-04-18T09:28:51+00:00","author":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d"},"breadcrumb":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.votorantimcimentos.es\/es\/noticias\/cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva\/#primaryimage","url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/20180103-banco-de-alimentos-scaled.jpg","contentUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/20180103-banco-de-alimentos-scaled.jpg","width":2560,"height":1439,"caption":"Donaci\u00f3n al Banco de Alimentos"},{"@type":"BreadcrumbList","@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/cementos-cosmos-y-sus-empleados-reunen-dinero-y-alimentos-para-el-banco-de-alimentos-de-huelva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.votorantimcimentos.es\/es\/"},{"@type":"ListItem","position":2,"name":"Cementos Cosmos y sus empleados re\u00fanen dinero y alimentos para el banco de alimentos de Huelva"}]},{"@type":"WebSite","@id":"https:\/\/www.votorantimcimentos.es\/es\/#website","url":"https:\/\/www.votorantimcimentos.es\/es\/","name":"Votorantim Cimentos Espa\u00f1a","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.votorantimcimentos.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.votorantimcimentos.es\/es\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d","name":"teconsite","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","caption":"teconsite"},"sameAs":["https:\/\/www.votorantimcimentos.es"],"url":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/author\/teconsite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts\/25107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/comments?post=25107"}],"version-history":[{"count":1,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts\/25107\/revisions"}],"predecessor-version":[{"id":25110,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts\/25107\/revisions\/25110"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/media\/25108"}],"wp:attachment":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/media?parent=25107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/categories?post=25107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/tags?post=25107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}