{"id":23612,"date":"2019-01-10T08:25:08","date_gmt":"2019-01-10T07:25:08","guid":{"rendered":"https:\/\/www.votorantimcimentos.es\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes\/"},"modified":"2024-04-18T11:28:01","modified_gmt":"2024-04-18T09:28:01","slug":"la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes","status":"publish","type":"post","link":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes\/","title":{"rendered":"La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba celebra seis a\u00f1os sin accidentes"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>C\u00f3rdoba, 10 de enero de 2019.- La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba ha alcanzado los seis a\u00f1os sin accidentes con baja entre sus trabajadores directos. Este hito representa alrededor de 460.000 horas laborables sin lesiones.<\/p>\n<p>El director de la planta, Jos\u00e9 de la Vega, ha recordado que este hecho se debe, principalmente, a \u00ablas iniciativas destinadas a fomentar la seguridad de la plantilla, que pasan por promover la concienciaci\u00f3n de los empleados a la hora de adoptar comportamientos seguros en los puestos de trabajo\u00bb.<\/p>\n<p>En esta l\u00ednea, la f\u00e1brica de C\u00f3rdoba ha puesto en marcha los Di\u00e1logos Diarios de Seguridad, donde los trabajadores comparten a primera hora de la ma\u00f1ana sus inquietudes y conocimientos relacionados con buenas pr\u00e1cticas que minimicen los riesgos.<\/p>\n<p>El a\u00f1o pasado Votorantim Cimentos, propietaria de la cementera de C\u00f3rdoba, recibi\u00f3 el Premio \u00abEmpresa del A\u00f1o\u00bb Prevencionar 2018 en la categor\u00eda \u00abGran Empresa\u00bb. Este galard\u00f3n reconoci\u00f3 la labor destacable y el esfuerzo en la prevenci\u00f3n de los riesgos laborales, la promoci\u00f3n de la salud y el bienestar en la organizaci\u00f3n. El fall\u00f3 se decidi\u00f3 entre 367 candidaturas.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba ha alcanzado los seis a\u00f1os sin accidentes con baja entre sus trabajadores directos. Este hito representa alrededor de 460.000 horas laborables sin lesiones.<\/p>\n","protected":false},"author":1,"featured_media":23613,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[225,239],"tags":[],"class_list":["post-23612","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fabrica-de-cordoba","category-sostenibilidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba celebra seis a\u00f1os sin accidentes | Votorantim Cimentos Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba celebra seis a\u00f1os sin accidentes | Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba ha alcanzado los seis a\u00f1os sin accidentes con baja entre sus trabajadores directos. Este hito representa alrededor de 460.000 horas laborables sin lesiones.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes\/\" \/>\n<meta property=\"og:site_name\" content=\"Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-10T07:25:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-18T09:28:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/20190110-6-anos-cordoba.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"teconsite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"teconsite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes\\\/\"},\"author\":{\"name\":\"teconsite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\"},\"headline\":\"La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba celebra seis a\u00f1os sin accidentes\",\"datePublished\":\"2019-01-10T07:25:08+00:00\",\"dateModified\":\"2024-04-18T09:28:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes\\\/\"},\"wordCount\":815,\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/20190110-6-anos-cordoba.jpg\",\"articleSection\":[\"F\u00e1brica de C\u00f3rdoba\",\"Sostenibilidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes\\\/\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes\\\/\",\"name\":\"La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba celebra seis a\u00f1os sin accidentes | Votorantim Cimentos Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/20190110-6-anos-cordoba.jpg\",\"datePublished\":\"2019-01-10T07:25:08+00:00\",\"dateModified\":\"2024-04-18T09:28:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/20190110-6-anos-cordoba.jpg\",\"contentUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/20190110-6-anos-cordoba.jpg\",\"width\":1000,\"height\":750,\"caption\":\"6 a\u00f1os sin accidentes en la f\u00e1brica de C\u00f3rdoba\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba celebra seis a\u00f1os sin accidentes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/\",\"name\":\"Votorantim Cimentos Espa\u00f1a\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\",\"name\":\"teconsite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"caption\":\"teconsite\"},\"sameAs\":[\"https:\\\/\\\/www.votorantimcimentos.es\"],\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/author\\\/teconsite\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba celebra seis a\u00f1os sin accidentes | Votorantim Cimentos Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes\/","og_locale":"es_ES","og_type":"article","og_title":"La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba celebra seis a\u00f1os sin accidentes | Votorantim Cimentos Espa\u00f1a","og_description":"La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba ha alcanzado los seis a\u00f1os sin accidentes con baja entre sus trabajadores directos. Este hito representa alrededor de 460.000 horas laborables sin lesiones.","og_url":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes\/","og_site_name":"Votorantim Cimentos Espa\u00f1a","article_published_time":"2019-01-10T07:25:08+00:00","article_modified_time":"2024-04-18T09:28:01+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/20190110-6-anos-cordoba.jpg","type":"image\/jpeg"}],"author":"teconsite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"teconsite","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes\/#article","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes\/"},"author":{"name":"teconsite","@id":"https:\/\/www.votorantimcimentos.es\/es\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d"},"headline":"La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba celebra seis a\u00f1os sin accidentes","datePublished":"2019-01-10T07:25:08+00:00","dateModified":"2024-04-18T09:28:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes\/"},"wordCount":815,"image":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/20190110-6-anos-cordoba.jpg","articleSection":["F\u00e1brica de C\u00f3rdoba","Sostenibilidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes\/","url":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes\/","name":"La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba celebra seis a\u00f1os sin accidentes | Votorantim Cimentos Espa\u00f1a","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes\/#primaryimage"},"image":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/20190110-6-anos-cordoba.jpg","datePublished":"2019-01-10T07:25:08+00:00","dateModified":"2024-04-18T09:28:01+00:00","author":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d"},"breadcrumb":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes\/#primaryimage","url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/20190110-6-anos-cordoba.jpg","contentUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/20190110-6-anos-cordoba.jpg","width":1000,"height":750,"caption":"6 a\u00f1os sin accidentes en la f\u00e1brica de C\u00f3rdoba"},{"@type":"BreadcrumbList","@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-cordoba-celebra-seis-anos-sin-accidentes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.votorantimcimentos.es\/es\/"},{"@type":"ListItem","position":2,"name":"La f\u00e1brica de Cementos Cosmos en C\u00f3rdoba celebra seis a\u00f1os sin accidentes"}]},{"@type":"WebSite","@id":"https:\/\/www.votorantimcimentos.es\/es\/#website","url":"https:\/\/www.votorantimcimentos.es\/es\/","name":"Votorantim Cimentos Espa\u00f1a","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.votorantimcimentos.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.votorantimcimentos.es\/es\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d","name":"teconsite","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","caption":"teconsite"},"sameAs":["https:\/\/www.votorantimcimentos.es"],"url":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/author\/teconsite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts\/23612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/comments?post=23612"}],"version-history":[{"count":2,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts\/23612\/revisions"}],"predecessor-version":[{"id":24953,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts\/23612\/revisions\/24953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/media\/23613"}],"wp:attachment":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/media?parent=23612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/categories?post=23612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/tags?post=23612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}