{"id":23609,"date":"2019-01-11T08:25:08","date_gmt":"2019-01-11T07:25:08","guid":{"rendered":"https:\/\/www.votorantimcimentos.es\/noticias\/la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva\/"},"modified":"2024-04-18T11:28:00","modified_gmt":"2024-04-18T09:28:00","slug":"la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva","status":"publish","type":"post","link":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva\/","title":{"rendered":"La f\u00e1brica de Cementos Cosmos en Niebla dona 1.800 kilos de comida al Banco de Alimentos de Huelva"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>Niebla, 11 de enero de 2019.- Cementos Cosmos, el Comit\u00e9 de Empresa y los trabajadores de la f\u00e1brica de Niebla han realizado una donaci\u00f3n de 1.800 kilos de productos no perecederos para el Banco de Alimentos de Huelva. Este proyecto es una iniciativa de la plantilla de la f\u00e1brica de Niebla y \u00e9ste es el tercer a\u00f1o consecutivo que se realiza para mostrar la solidaridad con las familias m\u00e1s desfavorecidas y con menos recursos de la provincia.<\/p>\n<p>Al acto de entrega, que ha tenido lugar en las instalaciones de la cementera, han asistido representantes de la empresa y de los trabajadores, as\u00ed como de Banco de Alimentos.<\/p>\n<p>Los empleados de la cementera de Niebla y sus representantes sindicales se vuelcan con iniciativas solidarias, apoyando causas humanitarias en el entorno. El a\u00f1o pasado lideraron una recogida de tapones para la Fundaci\u00f3n Seur destinados a su reciclaje y con el que se financian tratamientos m\u00e9dicos y ortopedias para ni\u00f1os. Una colaboraci\u00f3n con C\u00e1ritas llev\u00f3 a los trabajadores de Cosmos a protagonizar una recogida de ropa y otra de pa\u00f1ales. Y en el \u00e1mbito sanitario, y como ocurre en los \u00faltimos a\u00f1os, la plantilla particip\u00f3 en una donaci\u00f3n de sangre que se realiz\u00f3 en las instalaciones de la planta.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cementos Cosmos, el Comit\u00e9 de Empresa y los trabajadores de la f\u00e1brica de Niebla han realizado, por tercer a\u00f1o consecutivo, una donaci\u00f3n de 1.800 kilos de productos no perecederos para el Banco de Alimentos de Huelva.<\/p>\n","protected":false},"author":1,"featured_media":23610,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[227,239],"tags":[],"class_list":["post-23609","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fabrica-de-niebla","category-sostenibilidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La f\u00e1brica de Cementos Cosmos en Niebla dona 1.800 kilos de comida al Banco de Alimentos de Huelva | Votorantim Cimentos Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La f\u00e1brica de Cementos Cosmos en Niebla dona 1.800 kilos de comida al Banco de Alimentos de Huelva | Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"Cementos Cosmos, el Comit\u00e9 de Empresa y los trabajadores de la f\u00e1brica de Niebla han realizado, por tercer a\u00f1o consecutivo, una donaci\u00f3n de 1.800 kilos de productos no perecederos para el Banco de Alimentos de Huelva.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva\/\" \/>\n<meta property=\"og:site_name\" content=\"Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-11T07:25:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-18T09:28:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/20190111-cosmos-banco-alimentos-huelva.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"teconsite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"teconsite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva\\\/\"},\"author\":{\"name\":\"teconsite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\"},\"headline\":\"La f\u00e1brica de Cementos Cosmos en Niebla dona 1.800 kilos de comida al Banco de Alimentos de Huelva\",\"datePublished\":\"2019-01-11T07:25:08+00:00\",\"dateModified\":\"2024-04-18T09:28:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva\\\/\"},\"wordCount\":840,\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/20190111-cosmos-banco-alimentos-huelva.jpg\",\"articleSection\":[\"F\u00e1brica de Niebla\",\"Sostenibilidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva\\\/\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva\\\/\",\"name\":\"La f\u00e1brica de Cementos Cosmos en Niebla dona 1.800 kilos de comida al Banco de Alimentos de Huelva | Votorantim Cimentos Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/20190111-cosmos-banco-alimentos-huelva.jpg\",\"datePublished\":\"2019-01-11T07:25:08+00:00\",\"dateModified\":\"2024-04-18T09:28:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/20190111-cosmos-banco-alimentos-huelva.jpg\",\"contentUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/20190111-cosmos-banco-alimentos-huelva.jpg\",\"width\":1000,\"height\":750,\"caption\":\"Cosmos Banco Alimentos Huelva\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La f\u00e1brica de Cementos Cosmos en Niebla dona 1.800 kilos de comida al Banco de Alimentos de Huelva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/\",\"name\":\"Votorantim Cimentos Espa\u00f1a\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\",\"name\":\"teconsite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"caption\":\"teconsite\"},\"sameAs\":[\"https:\\\/\\\/www.votorantimcimentos.es\"],\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/author\\\/teconsite\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La f\u00e1brica de Cementos Cosmos en Niebla dona 1.800 kilos de comida al Banco de Alimentos de Huelva | Votorantim Cimentos Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva\/","og_locale":"es_ES","og_type":"article","og_title":"La f\u00e1brica de Cementos Cosmos en Niebla dona 1.800 kilos de comida al Banco de Alimentos de Huelva | Votorantim Cimentos Espa\u00f1a","og_description":"Cementos Cosmos, el Comit\u00e9 de Empresa y los trabajadores de la f\u00e1brica de Niebla han realizado, por tercer a\u00f1o consecutivo, una donaci\u00f3n de 1.800 kilos de productos no perecederos para el Banco de Alimentos de Huelva.","og_url":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva\/","og_site_name":"Votorantim Cimentos Espa\u00f1a","article_published_time":"2019-01-11T07:25:08+00:00","article_modified_time":"2024-04-18T09:28:00+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/20190111-cosmos-banco-alimentos-huelva.jpg","type":"image\/jpeg"}],"author":"teconsite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"teconsite","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva\/#article","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva\/"},"author":{"name":"teconsite","@id":"https:\/\/www.votorantimcimentos.es\/es\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d"},"headline":"La f\u00e1brica de Cementos Cosmos en Niebla dona 1.800 kilos de comida al Banco de Alimentos de Huelva","datePublished":"2019-01-11T07:25:08+00:00","dateModified":"2024-04-18T09:28:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva\/"},"wordCount":840,"image":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/20190111-cosmos-banco-alimentos-huelva.jpg","articleSection":["F\u00e1brica de Niebla","Sostenibilidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva\/","url":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva\/","name":"La f\u00e1brica de Cementos Cosmos en Niebla dona 1.800 kilos de comida al Banco de Alimentos de Huelva | Votorantim Cimentos Espa\u00f1a","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva\/#primaryimage"},"image":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/20190111-cosmos-banco-alimentos-huelva.jpg","datePublished":"2019-01-11T07:25:08+00:00","dateModified":"2024-04-18T09:28:00+00:00","author":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d"},"breadcrumb":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva\/#primaryimage","url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/20190111-cosmos-banco-alimentos-huelva.jpg","contentUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/20190111-cosmos-banco-alimentos-huelva.jpg","width":1000,"height":750,"caption":"Cosmos Banco Alimentos Huelva"},{"@type":"BreadcrumbList","@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/la-fabrica-de-cementos-cosmos-en-niebla-dona-1-800-kilos-de-comida-al-banco-de-alimentos-de-huelva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.votorantimcimentos.es\/es\/"},{"@type":"ListItem","position":2,"name":"La f\u00e1brica de Cementos Cosmos en Niebla dona 1.800 kilos de comida al Banco de Alimentos de Huelva"}]},{"@type":"WebSite","@id":"https:\/\/www.votorantimcimentos.es\/es\/#website","url":"https:\/\/www.votorantimcimentos.es\/es\/","name":"Votorantim Cimentos Espa\u00f1a","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.votorantimcimentos.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.votorantimcimentos.es\/es\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d","name":"teconsite","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","caption":"teconsite"},"sameAs":["https:\/\/www.votorantimcimentos.es"],"url":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/author\/teconsite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts\/23609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/comments?post=23609"}],"version-history":[{"count":2,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts\/23609\/revisions"}],"predecessor-version":[{"id":24952,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts\/23609\/revisions\/24952"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/media\/23610"}],"wp:attachment":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/media?parent=23609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/categories?post=23609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/tags?post=23609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}