{"id":23606,"date":"2019-01-30T08:25:08","date_gmt":"2019-01-30T07:25:08","guid":{"rendered":"https:\/\/www.votorantimcimentos.es\/noticias\/suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas\/"},"modified":"2024-04-18T11:28:00","modified_gmt":"2024-04-18T09:28:00","slug":"suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas","status":"publish","type":"post","link":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas\/","title":{"rendered":"Su\u00e1rez-Qui\u00f1ones entrega a Cosmos el reconocimiento como empresa adherida al sistema EMAS"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>Toral de los Vados, 30 de enero de 2019.- El consejero de Fomento y Medio Ambiente de la Junta de Castilla y Le\u00f3n, Juan Carlos Su\u00e1rez-Qui\u00f1ones, ha entregado a la f\u00e1brica de Cementos Cosmos en Toral de los Vados el reconocimiento como empresa adherida al Sistema Comunitario de Gesti\u00f3n y Auditor\u00eda Medioambientales (EMAS) en 2018. Esta certificaci\u00f3n es un mecanismo al que se someten voluntariamente las compa\u00f1\u00edas que desean adoptar criterios avanzados de sostenibilidad.<\/p>\n<p>Durante el acto de entrega, que ha tenido lugar esta ma\u00f1ana en la consejer\u00eda de Fomento y Medio Ambiente, Su\u00e1rez-Qui\u00f1ones ha asegurado que \u00abla certificaci\u00f3n EMAS es el sistema de gesti\u00f3n medioambiental voluntario m\u00e1s exigente que las empresas pueden tener en la UE y sirve como herramienta de mejora continua del comportamiento medioambiental\u00bb.<\/p>\n<p>Por parte de Cementos Cosmos ha recibido el galard\u00f3n Alan Svaiter, CEO de Votorantim Cimentos en Espa\u00f1a, que ha explicado que \u00abla adhesi\u00f3n al sistema EMAS es un ejercicio de transparencia y un ejemplo de excelencia en la gesti\u00f3n ambiental y ahora podemos decir que estamos orgullosos de formar parte de la veintena de empresas de Castilla y Le\u00f3n que cuentan con esta certificaci\u00f3n\u00bb.<\/p>\n<p><strong>Instrumento europeo de gesti\u00f3n<\/strong><\/p>\n<p>EMAS es una herramienta desarrollada por la Comisi\u00f3n Europea para evaluar, mejorar y comunicar el desempe\u00f1o medioambiental de empresas y organizaciones. Con este nuevo paso, Cementos Cosmos refuerza su apuesta por la transparencia, proporcionando informaci\u00f3n sobre este \u00e1mbito f\u00e1cilmente accesible para los ciudadanos a trav\u00e9s de la p\u00e1gina web de la compa\u00f1\u00eda.<\/p>\n<p>Como empresa adherida a este sistema, la cementera se compromete voluntariamente a evaluar y mejorar su impacto ambiental, proceso que ser\u00e1 auditado y verificado por terceros para garantizar su credibilidad.\u200b<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El consejero de Fomento y Medio Ambiente de la Junta de Castilla y Le\u00f3n ha entregado a la f\u00e1brica de Cementos Cosmos en Toral de los Vados el reconocimiento como empresa adherida al Sistema Comunitario de Gesti\u00f3n y Auditor\u00eda Medioambientales.<\/p>\n","protected":false},"author":1,"featured_media":23607,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[242,239],"tags":[],"class_list":["post-23606","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-premios-y-reconocimientos","category-sostenibilidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Su\u00e1rez-Qui\u00f1ones entrega a Cosmos el reconocimiento como empresa adherida al sistema EMAS | Votorantim Cimentos Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.votorantimcimentos.es\/es\/noticias\/suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Su\u00e1rez-Qui\u00f1ones entrega a Cosmos el reconocimiento como empresa adherida al sistema EMAS | Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"El consejero de Fomento y Medio Ambiente de la Junta de Castilla y Le\u00f3n ha entregado a la f\u00e1brica de Cementos Cosmos en Toral de los Vados el reconocimiento como empresa adherida al Sistema Comunitario de Gesti\u00f3n y Auditor\u00eda Medioambientales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.votorantimcimentos.es\/es\/noticias\/suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas\/\" \/>\n<meta property=\"og:site_name\" content=\"Votorantim Cimentos Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-30T07:25:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-18T09:28:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/20190130-certificacin-emas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"teconsite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"teconsite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas\\\/\"},\"author\":{\"name\":\"teconsite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\"},\"headline\":\"Su\u00e1rez-Qui\u00f1ones entrega a Cosmos el reconocimiento como empresa adherida al sistema EMAS\",\"datePublished\":\"2019-01-30T07:25:08+00:00\",\"dateModified\":\"2024-04-18T09:28:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas\\\/\"},\"wordCount\":922,\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/20190130-certificacin-emas.jpg\",\"articleSection\":[\"Premios y Reconocimientos\",\"Sostenibilidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas\\\/\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas\\\/\",\"name\":\"Su\u00e1rez-Qui\u00f1ones entrega a Cosmos el reconocimiento como empresa adherida al sistema EMAS | Votorantim Cimentos Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/20190130-certificacin-emas.jpg\",\"datePublished\":\"2019-01-30T07:25:08+00:00\",\"dateModified\":\"2024-04-18T09:28:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/20190130-certificacin-emas.jpg\",\"contentUrl\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/20190130-certificacin-emas.jpg\",\"width\":1000,\"height\":667,\"caption\":\"Certificaci\u00f3n EMAS\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Su\u00e1rez-Qui\u00f1ones entrega a Cosmos el reconocimiento como empresa adherida al sistema EMAS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/\",\"name\":\"Votorantim Cimentos Espa\u00f1a\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/#\\\/schema\\\/person\\\/f78a035d1ed9aae8be0efa59c718ae5d\",\"name\":\"teconsite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g\",\"caption\":\"teconsite\"},\"sameAs\":[\"https:\\\/\\\/www.votorantimcimentos.es\"],\"url\":\"https:\\\/\\\/www.votorantimcimentos.es\\\/es\\\/noticias\\\/author\\\/teconsite\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Su\u00e1rez-Qui\u00f1ones entrega a Cosmos el reconocimiento como empresa adherida al sistema EMAS | Votorantim Cimentos Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas\/","og_locale":"es_ES","og_type":"article","og_title":"Su\u00e1rez-Qui\u00f1ones entrega a Cosmos el reconocimiento como empresa adherida al sistema EMAS | Votorantim Cimentos Espa\u00f1a","og_description":"El consejero de Fomento y Medio Ambiente de la Junta de Castilla y Le\u00f3n ha entregado a la f\u00e1brica de Cementos Cosmos en Toral de los Vados el reconocimiento como empresa adherida al Sistema Comunitario de Gesti\u00f3n y Auditor\u00eda Medioambientales.","og_url":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas\/","og_site_name":"Votorantim Cimentos Espa\u00f1a","article_published_time":"2019-01-30T07:25:08+00:00","article_modified_time":"2024-04-18T09:28:00+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/20190130-certificacin-emas.jpg","type":"image\/jpeg"}],"author":"teconsite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"teconsite","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas\/#article","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas\/"},"author":{"name":"teconsite","@id":"https:\/\/www.votorantimcimentos.es\/es\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d"},"headline":"Su\u00e1rez-Qui\u00f1ones entrega a Cosmos el reconocimiento como empresa adherida al sistema EMAS","datePublished":"2019-01-30T07:25:08+00:00","dateModified":"2024-04-18T09:28:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas\/"},"wordCount":922,"image":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/20190130-certificacin-emas.jpg","articleSection":["Premios y Reconocimientos","Sostenibilidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas\/","url":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas\/","name":"Su\u00e1rez-Qui\u00f1ones entrega a Cosmos el reconocimiento como empresa adherida al sistema EMAS | Votorantim Cimentos Espa\u00f1a","isPartOf":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas\/#primaryimage"},"image":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/20190130-certificacin-emas.jpg","datePublished":"2019-01-30T07:25:08+00:00","dateModified":"2024-04-18T09:28:00+00:00","author":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d"},"breadcrumb":{"@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.votorantimcimentos.es\/es\/noticias\/suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas\/#primaryimage","url":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/20190130-certificacin-emas.jpg","contentUrl":"https:\/\/www.votorantimcimentos.es\/wp-content\/uploads\/2023\/12\/20190130-certificacin-emas.jpg","width":1000,"height":667,"caption":"Certificaci\u00f3n EMAS"},{"@type":"BreadcrumbList","@id":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/suarez-quinones-entrega-a-cosmos-el-reconocimiento-como-empresa-adherida-al-sistema-emas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.votorantimcimentos.es\/es\/"},{"@type":"ListItem","position":2,"name":"Su\u00e1rez-Qui\u00f1ones entrega a Cosmos el reconocimiento como empresa adherida al sistema EMAS"}]},{"@type":"WebSite","@id":"https:\/\/www.votorantimcimentos.es\/es\/#website","url":"https:\/\/www.votorantimcimentos.es\/es\/","name":"Votorantim Cimentos Espa\u00f1a","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.votorantimcimentos.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.votorantimcimentos.es\/es\/#\/schema\/person\/f78a035d1ed9aae8be0efa59c718ae5d","name":"teconsite","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/21ab8f11664119780e77855bcb9750ce470b4b8d4f7bfd804b9dd51b89b537bd?s=96&d=mm&r=g","caption":"teconsite"},"sameAs":["https:\/\/www.votorantimcimentos.es"],"url":"https:\/\/www.votorantimcimentos.es\/es\/noticias\/author\/teconsite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts\/23606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/comments?post=23606"}],"version-history":[{"count":2,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts\/23606\/revisions"}],"predecessor-version":[{"id":24950,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/posts\/23606\/revisions\/24950"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/media\/23607"}],"wp:attachment":[{"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/media?parent=23606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/categories?post=23606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.votorantimcimentos.es\/es\/wp-json\/wp\/v2\/tags?post=23606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}